{"id":87640,"date":"2016-09-04T02:12:45","date_gmt":"2016-09-04T05:12:45","guid":{"rendered":"http:\/\/notinor.com\/jujuy\/?p=87640"},"modified":"2016-09-04T22:25:45","modified_gmt":"2016-09-05T01:25:45","slug":"atraparon-un-tucan-y-le-cortaron-las-alas","status":"publish","type":"post","link":"https:\/\/notinor.com\/jujuy\/atraparon-un-tucan-y-le-cortaron-las-alas\/","title":{"rendered":"Atraparon un tuc\u00e1n y le cortaron las alas"},"content":{"rendered":"<p><a href=\"http:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2016\/09\/tucan-maltratado.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-87641\" src=\"http:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2016\/09\/tucan-maltratado.jpg\" alt=\"tucan maltratado\" width=\"800\" height=\"509\" srcset=\"https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2016\/09\/tucan-maltratado.jpg 800w, https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2016\/09\/tucan-maltratado-300x191.jpg 300w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n<p>J\u00f3venes salte\u00f1os de la localidad de Met\u00e1n, encontraron un tucan al lque le cortaron las alas y lo arrojaron a la calle. Mientras hac\u00edan esta atrocidad, lo filmaron y subieron el video a las redes sociales lo que ocasiono el repudio masivo de toda la comunidad.<\/p>\n<p>Luego de realizar este repudiable hecho lo arrojaron a la calle y le habr\u00edan provocado la muerte.<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/tnFPdcoeNXo\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>J\u00f3venes salte\u00f1os de la localidad de Met\u00e1n, encontraron un tucan al lque le cortaron las alas y lo arrojaron a la calle. Mientras hac\u00edan esta atrocidad, lo filmaron y subieron el video a las redes sociales lo que ocasiono el repudio masivo de toda la comunidad. Luego de realizar este repudiable hecho lo arrojaron a [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":87641,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_stopmodifiedupdate":false,"_modified_date":"","inline_featured_image":false,"spay_email":"","jetpack_publicize_message":""},"categories":[489,488],"tags":[],"jetpack_featured_media_url":"https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2016\/09\/tucan-maltratado.jpg","jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts\/87640"}],"collection":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/comments?post=87640"}],"version-history":[{"count":2,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts\/87640\/revisions"}],"predecessor-version":[{"id":87643,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts\/87640\/revisions\/87643"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/media\/87641"}],"wp:attachment":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/media?parent=87640"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/categories?post=87640"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/tags?post=87640"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}