{"id":82897,"date":"2016-08-01T09:17:56","date_gmt":"2016-08-01T12:17:56","guid":{"rendered":"http:\/\/notinor.com\/jujuy\/?p=82897"},"modified":"2016-08-02T10:20:52","modified_gmt":"2016-08-02T13:20:52","slug":"una-tarde-a-pura-diversion-en-el-parque-san-martin","status":"publish","type":"post","link":"https:\/\/notinor.com\/jujuy\/una-tarde-a-pura-diversion-en-el-parque-san-martin\/","title":{"rendered":"Una tarde a pura \u201cDiversi\u00f3n\u201d en el Parque San Mart\u00edn"},"content":{"rendered":"<p>En el Parque San Mart\u00edn, los payasos Yogursito, Cucharita y Cuchar\u00f3n, dieron un espect\u00e1culo colorido para los m\u00e1s peque\u00f1os, una de las opciones que el municipio capitalino propuso para este tiempo de vacaciones de invierno donde se tuvo dos semanas a pura cultura y diversi\u00f3n para toda la familia.<\/p>\n<p>En esa oportunidad, el Director de Cultura, Memo Vilte, expres\u00f3 \u201crealmente contentos porque fueron unas vacaciones distintas, arte en mi barrio y una semana de payasos para que la familia disfrute gratuitamente con magos, payasos y t\u00edteres\u2026nos propusimos a principio de a\u00f1o, que este sea un Julio distinto, un julio cultural con muchas actividades, por eso pudimos ver en la calle grupos tocando, gente bailando, se sum\u00f3 a esto la tradicional fiesta de los artesanos\u201d<\/p>\n<p>Teatro, m\u00fasica, artesan\u00edas, gastronom\u00eda, danzas y juegos para los ni\u00f1os fueron el resultados de las Vacaciones de Invierno en \u202a#\u200eTuCiudad.\u201d<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En el Parque San Mart\u00edn, los payasos Yogursito, Cucharita y Cuchar\u00f3n, dieron un espect\u00e1culo colorido para los m\u00e1s peque\u00f1os, una de las opciones que el municipio capitalino propuso para este tiempo de vacaciones de invierno donde se tuvo dos semanas a pura cultura y diversi\u00f3n para toda la familia. En esa oportunidad, el Director de [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":82898,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_stopmodifiedupdate":false,"_modified_date":"","inline_featured_image":false},"categories":[490],"tags":[],"jetpack_featured_media_url":"https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2016\/08\/payasos.jpg","_links":{"self":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts\/82897"}],"collection":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/comments?post=82897"}],"version-history":[{"count":1,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts\/82897\/revisions"}],"predecessor-version":[{"id":82899,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts\/82897\/revisions\/82899"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/media\/82898"}],"wp:attachment":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/media?parent=82897"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/categories?post=82897"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/tags?post=82897"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}