{"id":46825,"date":"2015-10-06T00:49:09","date_gmt":"2015-10-06T03:49:09","guid":{"rendered":"http:\/\/notinor.com\/jujuy\/?p=46825"},"modified":"2015-10-06T00:49:53","modified_gmt":"2015-10-06T03:49:53","slug":"una-adolescente-fue-encontrada-sin-vida-en-alto-comedero","status":"publish","type":"post","link":"https:\/\/notinor.com\/jujuy\/una-adolescente-fue-encontrada-sin-vida-en-alto-comedero\/","title":{"rendered":"Una adolescente fue encontrada sin vida en Alto Comedero"},"content":{"rendered":"<p>Una adolescente identificada como ISIS AYLAN de 17 a\u00f1os, fue encontrada sin vida y pendiendo del cuello de la rama de un \u00e1rbol, en la ma\u00f1ana de hoy. El tr\u00e1gico cuadro fue descubierto y denunciado por vecinos del sector conocido como La Loma, del B\u00b0 Alto Comedero. Aunque una versi\u00f3n que circula entre los allegados de la v\u00edctima, hace menci\u00f3n que en la noche del s\u00e1bado Isis mantuvo una acalorada discusi\u00f3n con su pareja, por celos del individuo.<\/p>\n<p>Hip\u00f3tesis que esta siendo investigada por la polic\u00eda.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>fuente policiales de jujuy<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una adolescente identificada como ISIS AYLAN de 17 a\u00f1os, fue encontrada sin vida y pendiendo del cuello de la rama de un \u00e1rbol, en la ma\u00f1ana de hoy. El tr\u00e1gico cuadro fue descubierto y denunciado por vecinos del sector conocido como La Loma, del B\u00b0 Alto Comedero. Aunque una versi\u00f3n que circula entre los allegados [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":46828,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_stopmodifiedupdate":false,"_modified_date":"","inline_featured_image":false},"categories":[3],"tags":[],"jetpack_featured_media_url":"https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2015\/10\/policiales.jpg","_links":{"self":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts\/46825"}],"collection":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/comments?post=46825"}],"version-history":[{"count":2,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts\/46825\/revisions"}],"predecessor-version":[{"id":46830,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts\/46825\/revisions\/46830"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/media\/46828"}],"wp:attachment":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/media?parent=46825"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/categories?post=46825"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/tags?post=46825"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}