{"id":46759,"date":"2015-10-06T00:02:49","date_gmt":"2015-10-06T03:02:49","guid":{"rendered":"http:\/\/notinor.com\/jujuy\/?p=46759"},"modified":"2015-10-05T20:52:58","modified_gmt":"2015-10-05T23:52:58","slug":"eeuu-y-11-paises-del-pacifico-crearon-la-mayor-zona-de-libre-comercio-del-mundo","status":"publish","type":"post","link":"https:\/\/notinor.com\/jujuy\/eeuu-y-11-paises-del-pacifico-crearon-la-mayor-zona-de-libre-comercio-del-mundo\/","title":{"rendered":"EEUU y 11 pa\u00edses del Pac\u00edfico crearon la mayor zona de libre comercio del mundo"},"content":{"rendered":"<p>El Tratado de Asociaci\u00f3n Transpac\u00edfico representa el 40% de la econom\u00eda mundial. Barack Obama dijo que beneficiar\u00e1 a empresas y trabajadores de su pa\u00eds. Las tres naciones latinoamericanas involucradas<\/p>\n<p>Los Estados Unidos alcanzaron este lunes un acuerdo con 11 naciones del Pac\u00edfico para el m\u00e1s ambicioso acuerdo comercial jam\u00e1s alcanzado, que representa el 40% de la econom\u00eda mundial.<\/p>\n<p>El acuerdo final, alcanzado tras limar las diferencias entre los EEUU y Jap\u00f3n, las dos mayores econom\u00edas de este grupo, pone en v\u00eda de aprobaci\u00f3n al importante Tratado de Asociaci\u00f3n Transpac\u00edfico (TTP, por su sigla en ingl\u00e9s).<\/p>\n<p>El acuerdo es resultado de arduas negociaciones desde el mi\u00e9rcoles en Atlanta (Georgia, EEUU), donde se esperaban solucionar las \u00faltimas diferencias t\u00e9cnicas.<\/p>\n<p>Los negociadores hab\u00edan retrasado el anuncio conocido hoy por diferencias sobre el acceso al mercado de productos l\u00e1cteos y sobre la nueva generaci\u00f3n de biomedicina.<\/p>\n<p>El ministro japon\u00e9s de Pol\u00edtica Econ\u00f3mica y Fiscal, Akira Amari, y el representante de Comercio de los Estados Unidos, Michael Froman, participaron en las conversaciones, que levantar\u00e1n las barreras al comercio entre las principales econom\u00edas ribere\u00f1as del Pac\u00edfico.<\/p>\n<p>El acuerdo del TPP, cuyas negociaciones comenzaron en 2008, concentrar\u00eda a doce econom\u00edas con salida al oc\u00e9ano Pac\u00edfico, y ha sido remarcado como una se\u00f1al de la importancia de la regi\u00f3n Asia-Pac\u00edfico, que cubre el 40 por ciento de la econom\u00eda mundial.<\/p>\n<p>Los pa\u00edses integrantes del TPP son, adem\u00e1s de los EEUU y Jap\u00f3n, Australia, Brunei, Canad\u00e1, Chile, Malasia, M\u00e9xico, Nueva Zelanda, Per\u00fa, Singapur y Vietnam.<\/p>\n<p>Las diferencias hab\u00edan sido m\u00e1s fuertes en los sectores agr\u00edcolas, de automoci\u00f3n, propiedad intelectual y productos farmac\u00e9uticos, entre otros.<\/p>\n<h2>Reacci\u00f3n de Obama<\/h2>\n<p>El presidente estadounidense, Barack Obama, que ha presionado para que avance este acuerdo y otro con la Uni\u00f3n Europea, alcanz\u00f3 una importante victoria esta primavera al conseguir que el Congreso acepte el tr\u00e1mite de pactos comerciales por la v\u00eda r\u00e1pida, con lo que s\u00f3lo podr\u00e1n aprobarlos o rechazarlos, pero no enmendarlos. No obstante, no se espera que el pacto pueda someterse a voto en el Congreso hasta el pr\u00f3ximo a\u00f1o.<\/p>\n<p>Obama sostuvo que el TPP \"nivelar\u00e1 el campo de juego\" para los trabajadores y empresas de su pa\u00eds.<\/p>\n<p>En un comunicado divulgado el lunes, Obama asegur\u00f3 que los estadounidenses tendr\u00edan meses para prepararse para el pacto antes de que lo promulgue.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Tratado de Asociaci\u00f3n Transpac\u00edfico representa el 40% de la econom\u00eda mundial. Barack Obama dijo que beneficiar\u00e1 a empresas y trabajadores de su pa\u00eds. Las tres naciones latinoamericanas involucradas Los Estados Unidos alcanzaron este lunes un acuerdo con 11 naciones del Pac\u00edfico para el m\u00e1s ambicioso acuerdo comercial jam\u00e1s alcanzado, que representa el 40% de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":46760,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_stopmodifiedupdate":false,"_modified_date":"","inline_featured_image":false},"categories":[6],"tags":[],"jetpack_featured_media_url":"https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2015\/10\/ttp.jpg","_links":{"self":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts\/46759"}],"collection":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/comments?post=46759"}],"version-history":[{"count":1,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts\/46759\/revisions"}],"predecessor-version":[{"id":46761,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts\/46759\/revisions\/46761"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/media\/46760"}],"wp:attachment":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/media?parent=46759"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/categories?post=46759"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/tags?post=46759"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}