{"id":442039,"date":"2026-05-12T23:14:00","date_gmt":"2026-05-13T02:14:00","guid":{"rendered":"https:\/\/notinor.com\/jujuy\/?p=442039"},"modified":"2026-05-12T11:14:21","modified_gmt":"2026-05-12T11:14:21","slug":"emotivo-homenaje-a-enfermeras-y-enfermeros-en-su-dia-internacional-2","status":"publish","type":"post","link":"https:\/\/notinor.com\/jujuy\/emotivo-homenaje-a-enfermeras-y-enfermeros-en-su-dia-internacional-2\/","title":{"rendered":"Emotivo homenaje a enfermeras y enfermeros en su d\u00eda internacional"},"content":{"rendered":"\n<p class=\"has-medium-font-size\"><strong><em>En el marco del D\u00eda Internacional de la Enfermer\u00eda, se realiz\u00f3 un acto de reconocimiento a las y los profesionales de la salud, destacando su vocaci\u00f3n de servicio, el compromiso humano con los pacientes y la importancia de la labor que desempe\u00f1an diariamente. La fecha conmemora adem\u00e1s el nacimiento de Florence Nightingale, considerada la primera enfermera profesional.<\/em><\/strong><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/www.sansalvadordejujuy.gob.ar\/wp-content\/uploads\/2026\/05\/dia-de-la-enfermeria-1024x561.jpg\" alt=\"\" class=\"wp-image-103941\"\/><\/figure><\/div>\n\n\n<p>La ceremonia comenz\u00f3 con la colocaci\u00f3n de una ofrenda floral al pie del monumento en homenaje al personal de enfermer\u00eda. Participaron el secretario de Desarrollo Humano, <strong>Gustavo Muro<\/strong>; la presidenta de la Asociaci\u00f3n Civil de Enfermer\u00eda, <strong>Isabel Nely P\u00e9rez;<\/strong> la rectora del Instituto \u201cMiriam Gloss\u201d, <strong>Viviana L\u00f3pe<\/strong>z; abanderados, delegaciones y funcionarios municipales.<\/p>\n\n\n\n<p>Tras el acto, Gustavo Muro destac\u00f3 la importancia de acompa\u00f1ar a \u201cquienes eligieron una profesi\u00f3n basada en la vocaci\u00f3n y la empat\u00eda, generando v\u00ednculos con los pacientes y humanizando la atenci\u00f3n\u201d.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/www.sansalvadordejujuy.gob.ar\/wp-content\/uploads\/2026\/05\/dia-de-la-enfermeria1-1024x575.jpg\" alt=\"\" class=\"wp-image-103942\"\/><\/figure><\/div>\n\n\n<p>Asimismo, el funcionario valor\u00f3 el reconocimiento al exintendente ,Hugo Cid Conde, por el significado simb\u00f3lico del espacio ubicado detr\u00e1s del Hospital Pablo Soria. En ese marco, reafirm\u00f3 el compromiso del municipio con la construcci\u00f3n de una comunidad saludable y subray\u00f3 que \u201clas y los enfermeros no solo tratan enfermedades, sino que tambi\u00e9n cumplen un rol fundamental en la prevenci\u00f3n y promoci\u00f3n de la salud\u201d.<\/p>\n\n\n\n<p>Durante la ceremonia, Isabel Nely P\u00e9rez expres\u00f3: \u201cCelebramos el D\u00eda Internacional de la Enfermer\u00eda, instituido por la OMS, coincidiendo con el natalicio de Florence Nightingale\u201d. Adem\u00e1s, record\u00f3 que desde hace 29 a\u00f1os \u201crealizamos este homenaje en el monolito ubicado frente a los principales hospitales de la provincia\u201d.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/www.sansalvadordejujuy.gob.ar\/wp-content\/uploads\/2026\/05\/dia-de-la-enfermeria3-1024x551.jpg\" alt=\"\" class=\"wp-image-103943\"\/><\/figure><\/div>\n\n\n<p>En ese sentido, destac\u00f3 especialmente el acompa\u00f1amiento que brind\u00f3 en su momento el exintendente, Hugo Cid Conde, quien \u201ccedi\u00f3 el espacio para emplazar el monumento pensando en que estuviera frente a los dos grandes hospitales: el Pablo Soria y el Hospital de Ni\u00f1os\u201d. Tambi\u00e9n adelant\u00f3 que el pr\u00f3ximo a\u00f1o, al cumplirse tres d\u00e9cadas del monolito, se llevar\u00e1 a cabo un homenaje especial en su memoria.<\/p>\n\n\n\n<p>P\u00e9rez agradeci\u00f3 adem\u00e1s el acompa\u00f1amiento permanente hacia el sector de enfermer\u00eda y felicit\u00f3 a todas las enfermeras y enfermeros en su d\u00eda \u201cpor acompa\u00f1arnos en esta fecha tan significativa\u201d.<\/p>\n\n\n\n<p>Por su parte, Viviana L\u00f3pez resalt\u00f3 el orgullo que siente por su profesi\u00f3n y afirm\u00f3: \u201cSi hay algo que ha coronado mi vida es esta profesi\u00f3n\u201d, destacando el valor humano y social de la enfermer\u00eda en el marco de la conmemoraci\u00f3n.<\/p>\n\n\n\n<p>Finalmente, remarc\u00f3 que \u201ceste a\u00f1o estar\u00e1 marcado por el empoderamiento de la enfermer\u00eda\u201d, entendiendo este concepto como el crecimiento y la evoluci\u00f3n que ha tenido la profesi\u00f3n a lo largo del tiempo. En ese sentido, se\u00f1al\u00f3 que en la provincia existe un importante n\u00famero de licenciados en enfermer\u00eda y sostuvo que una de las principales herramientas para fortalecer la profesi\u00f3n es la capacitaci\u00f3n permanente.<\/p>\n\n\n\n<p><strong>Nota audiovisual:<\/strong><a href=\"https:\/\/youtu.be\/19IEhWI_Rrs\">&nbsp;https:\/\/youtu.be\/19IEhWI_Rrs<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En el marco del D\u00eda Internacional de la Enfermer\u00eda, se realiz\u00f3 un acto de reconocimiento a las y los profesionales de la salud, destacando su vocaci\u00f3n de servicio, el compromiso humano con los pacientes y la importancia de la labor que desempe\u00f1an diariamente. La fecha conmemora adem\u00e1s el nacimiento de Florence Nightingale, considerada la primera [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":442040,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_stopmodifiedupdate":false,"_modified_date":"","inline_featured_image":false,"spay_email":"","jetpack_publicize_message":""},"categories":[13],"tags":[],"jetpack_featured_media_url":"https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2026\/05\/ENFERMEROS.jpg","jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts\/442039"}],"collection":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/comments?post=442039"}],"version-history":[{"count":1,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts\/442039\/revisions"}],"predecessor-version":[{"id":442041,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts\/442039\/revisions\/442041"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/media\/442040"}],"wp:attachment":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/media?parent=442039"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/categories?post=442039"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/tags?post=442039"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}