{"id":420130,"date":"2024-11-29T20:02:00","date_gmt":"2024-11-29T23:02:00","guid":{"rendered":"https:\/\/notinor.com\/jujuy\/?p=420130"},"modified":"2024-11-29T08:02:00","modified_gmt":"2024-11-29T08:02:00","slug":"este-domingo-ejesa-realizara-tareas-de-mejora-y-mantenimiento-de-redes-electricas-en-b-centro-de-san-pedro-2","status":"publish","type":"post","link":"https:\/\/notinor.com\/jujuy\/este-domingo-ejesa-realizara-tareas-de-mejora-y-mantenimiento-de-redes-electricas-en-b-centro-de-san-pedro-2\/","title":{"rendered":"Este domingo EJESA realizar\u00e1 tareas de mejora y mantenimiento de redes el\u00e9ctricas en B\u00b0 Centro de San Pedro"},"content":{"rendered":"\n<p class=\"has-medium-font-size\"><strong><em>\u00a0Informamos\u00a0que, con el objeto de\u00a0elevar la calidad de nuestro servicio,\u00a0se realizar\u00e1n tareas de\u00a0mantenimiento y renovaci\u00f3n\u00a0en las instalaciones de nuestro sistema.<\/em><\/strong><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2023\/03\/SAN-PEDRO.jpg\" alt=\"\" class=\"wp-image-374885\" width=\"642\" height=\"479\" srcset=\"https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2023\/03\/SAN-PEDRO.jpg 517w, https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2023\/03\/SAN-PEDRO-489x365.jpg 489w\" sizes=\"(max-width: 642px) 100vw, 642px\" \/><\/figure><\/div>\n\n\n<p>Con este fin, ser\u00e1 necesario efectuar una&nbsp;interrupci\u00f3n programada en las siguientes zonas y horarios:<\/p>\n\n\n\n<p>\ud83d\udcccSAN PEDRO DE JUJUY<\/p>\n\n\n\n<p>\ud83d\uddd3\ufe0f DOMINGO 01\/12\/2024&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<p>\ud83d\udd52&nbsp;De 07:30 a 11:30 Hs aprox.<\/p>\n\n\n\n<p>Zonas: B\u00b0 Centro (ente calles Guillermo Paterson, San Martin, Juan Alberdi, Alsina, Velez Sarfield, Aristobulo del Valle) y zonas aleda\u00f1as.<\/p>\n\n\n\n<p>Agradecemos tomar las precauciones necesarias durante la duraci\u00f3n de dicha interrupci\u00f3n a fin de evitar mayores inconvenientes.<\/p>\n\n\n\n<p>Por consultas y\/o requerimientos te recordamos nuestros canales oficiales de contacto disponibles las 24hs. A trav\u00e9s de este link:&nbsp;<a href=\"https:\/\/linktr.ee\/ejesa\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/linktr.ee\/ejesa<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0Informamos\u00a0que, con el objeto de\u00a0elevar la calidad de nuestro servicio,\u00a0se realizar\u00e1n tareas de\u00a0mantenimiento y renovaci\u00f3n\u00a0en las instalaciones de nuestro sistema. Con este fin, ser\u00e1 necesario efectuar una&nbsp;interrupci\u00f3n programada en las siguientes zonas y horarios: \ud83d\udcccSAN PEDRO DE JUJUY \ud83d\uddd3\ufe0f DOMINGO 01\/12\/2024&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; \ud83d\udd52&nbsp;De 07:30 a 11:30 Hs aprox. Zonas: B\u00b0 Centro (ente calles Guillermo Paterson, San [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":374885,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_stopmodifiedupdate":false,"_modified_date":"","inline_featured_image":false,"spay_email":"","jetpack_publicize_message":""},"categories":[4],"tags":[],"jetpack_featured_media_url":"https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2023\/03\/SAN-PEDRO.jpg","jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts\/420130"}],"collection":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/comments?post=420130"}],"version-history":[{"count":1,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts\/420130\/revisions"}],"predecessor-version":[{"id":420131,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts\/420130\/revisions\/420131"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/media\/374885"}],"wp:attachment":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/media?parent=420130"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/categories?post=420130"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/tags?post=420130"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}