{"id":417302,"date":"2024-10-14T23:01:30","date_gmt":"2024-10-15T02:01:30","guid":{"rendered":"https:\/\/notinor.com\/jujuy\/?p=417302"},"modified":"2024-10-14T23:01:33","modified_gmt":"2024-10-15T02:01:33","slug":"la-inflacion-del-mes-de-septiembre-en-jujuy-fue-25-y-acumula-916-en-el-ano","status":"publish","type":"post","link":"https:\/\/notinor.com\/jujuy\/la-inflacion-del-mes-de-septiembre-en-jujuy-fue-25-y-acumula-916-en-el-ano\/","title":{"rendered":"La inflaci\u00f3n del\u00a0mes de septiembre en Jujuy fue 2,5% y acumula 91,6% en el a\u00f1o"},"content":{"rendered":"\n<p class=\"has-medium-font-size\"><strong><em>La DIPEC inform\u00f3 que desde septiembre del 2023 al mismo mes del 2024, la inflaci\u00f3n en Jujuy fue de 191,6%.<\/em><\/strong><\/p>\n\n\n\n<p><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" loading=\"lazy\" width=\"800\" height=\"450\" src=\"https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2023\/09\/inflacion.jpg\" alt=\"\" class=\"wp-image-390580\" srcset=\"https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2023\/09\/inflacion.jpg 800w, https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2023\/09\/inflacion-649x365.jpg 649w, https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2023\/09\/inflacion-500x280.jpg 500w, https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2023\/09\/inflacion-768x432.jpg 768w, https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2023\/09\/inflacion-750x422.jpg 750w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure><\/div>\n\n\n<p><\/p>\n\n\n\n<p><strong>La Direcci\u00f3n Provincial de Estad\u00edstica y Censos (DIPEC) inform\u00f3 este lunes que la inflaci\u00f3n de septiembre en Jujuy fue del 2,5%, <\/strong>mientras la variaci\u00f3n registrada en los \u00faltimos 12 meses, que abarca de septiembre del 2023 al mismo mes de este a\u00f1o, es de 191,6%.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>Los rubros de la inflaci\u00f3n en Jujuy<\/strong><\/p>\n\n\n\n<ul>\n<li>Otros gastos: 10,9%<\/li>\n\n\n\n<li>Ense\u00f1anza: 5,5%<\/li>\n\n\n\n<li>Vivienda, combustible y electricidad: 4,6%<\/li>\n\n\n\n<li>Atenci\u00f3n m\u00e9dica y gastos para la salud: 3,7%<\/li>\n\n\n\n<li>Transporte y comunicaciones: 2,8%<\/li>\n\n\n\n<li>Indumentaria: 2%<\/li>\n\n\n\n<li>Alimentaci\u00f3n y bebidas: 1,9%<\/li>\n\n\n\n<li>Equipamiento y funcionamiento del hogar: 1,3%<\/li>\n\n\n\n<li>Esparcimiento: 0,3%<\/li>\n<\/ul>\n\n\n\n<p class=\"has-medium-font-size\"><strong>Inflaci\u00f3n interanual en cada rubro en Jujuy<\/strong><\/p>\n\n\n\n<ul>\n<li>Transporte y comunicaciones: 308,2%<\/li>\n\n\n\n<li>Otros gastos: 252,1%<\/li>\n\n\n\n<li>Vivienda, combustible y electricidad: 229,1%<\/li>\n\n\n\n<li>Atenci\u00f3n m\u00e9dica y gastos para la salud: 204,7%<\/li>\n\n\n\n<li>Esparcimiento: 203,5%<\/li>\n\n\n\n<li>Ense\u00f1anza: 202,9%<\/li>\n\n\n\n<li>Equipamiento y funcionamiento del hogar: 197,3%<\/li>\n\n\n\n<li>Alimentaci\u00f3n y bebidas: 191,6%<\/li>\n\n\n\n<li>Indumentaria: 120,6%<\/li>\n<\/ul>\n\n\n\n<p class=\"has-medium-font-size\"><strong>La inflaci\u00f3n de septiembre en Argentina fue de 3,5% y acumula 101,6%<\/strong><\/p>\n\n\n\n<p>El Instituto Nacional de Estad\u00edsticas y Censos (INDEC) anunci\u00f3 que la inflaci\u00f3n en Argentina durante el mes de septiembre fue de 3,5%, mientras que la suba de precios interanual lleg\u00f3 al 209% y la variaci\u00f3n acumulada del 2024 es del 101,6%.<\/p>\n\n\n\n<p><strong>Recordemos que en agosto la inflaci\u00f3n hab\u00eda sido de 4,2%, la interanual lleg\u00f3 al 236,7% y la variaci\u00f3n acumulada fue del 94,8%.<\/strong> La divisi\u00f3n de mayor aumento ese mes fue Vivienda, agua, electricidad y otros combustibles con un 7,0%.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La DIPEC inform\u00f3 que desde septiembre del 2023 al mismo mes del 2024, la inflaci\u00f3n en Jujuy fue de 191,6%. La Direcci\u00f3n Provincial de Estad\u00edstica y Censos (DIPEC) inform\u00f3 este lunes que la inflaci\u00f3n de septiembre en Jujuy fue del 2,5%, mientras la variaci\u00f3n registrada en los \u00faltimos 12 meses, que abarca de septiembre del [&hellip;]<\/p>\n","protected":false},"author":49,"featured_media":390580,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_stopmodifiedupdate":false,"_modified_date":"","inline_featured_image":false,"spay_email":"","jetpack_publicize_message":""},"categories":[2,676,514],"tags":[],"jetpack_featured_media_url":"https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2023\/09\/inflacion.jpg","jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts\/417302"}],"collection":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/users\/49"}],"replies":[{"embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/comments?post=417302"}],"version-history":[{"count":1,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts\/417302\/revisions"}],"predecessor-version":[{"id":417303,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts\/417302\/revisions\/417303"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/media\/390580"}],"wp:attachment":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/media?parent=417302"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/categories?post=417302"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/tags?post=417302"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}