{"id":415601,"date":"2024-09-13T22:43:37","date_gmt":"2024-09-14T01:43:37","guid":{"rendered":"https:\/\/notinor.com\/jujuy\/?p=415601"},"modified":"2024-09-13T22:43:42","modified_gmt":"2024-09-14T01:43:42","slug":"murio-alfredo-cahe-el-historico-medico-de-maradona-y-otros-famosos","status":"publish","type":"post","link":"https:\/\/notinor.com\/jujuy\/murio-alfredo-cahe-el-historico-medico-de-maradona-y-otros-famosos\/","title":{"rendered":"Muri\u00f3 Alfredo Cahe, el hist\u00f3rico m\u00e9dico de Maradona y otros famosos"},"content":{"rendered":"\n<p class=\"has-medium-font-size\"><strong><em>El profesional, que acompa\u00f1\u00f3 a Diego durante m\u00e1s de tres d\u00e9cadas, ten\u00eda 80 a\u00f1os.<\/em><\/strong><\/p>\n\n\n\n<p><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" loading=\"lazy\" width=\"800\" height=\"450\" src=\"https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2024\/09\/diego-maradona-y-alfredo-cahe.jpg\" alt=\"\" class=\"wp-image-415602\" srcset=\"https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2024\/09\/diego-maradona-y-alfredo-cahe.jpg 800w, https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2024\/09\/diego-maradona-y-alfredo-cahe-649x365.jpg 649w, https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2024\/09\/diego-maradona-y-alfredo-cahe-500x280.jpg 500w, https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2024\/09\/diego-maradona-y-alfredo-cahe-768x432.jpg 768w, https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2024\/09\/diego-maradona-y-alfredo-cahe-750x422.jpg 750w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><figcaption class=\"wp-element-caption\">Diego Maradona y Alfredo Cahe en el a\u00f1o 2000, la \u00e9poca en la que Diego estuvo en Cuba<\/figcaption><\/figure><\/div>\n\n\n<p><\/p>\n\n\n\n<p><strong>Alfredo Cahe, el hist\u00f3rico m\u00e9dico que acompa\u00f1\u00f3 a Diego Armando Maradona durante tres d\u00e9cadas y atendi\u00f3 a otros famosos durante su carrera, muri\u00f3 este viernes a los 80 a\u00f1os.<\/strong><\/p>\n\n\n\n<p><strong>\u201cCon profundo dolor despido a mi querido amigo Alfredo Cahe, reconocido por sus cualidades profesionales y humanas\u201d,<\/strong> escribi\u00f3 Daniel Scioli, secretario de Ambiente, Turismo y Deportes, en sus redes sociales, confirmando la noticia del fallecimiento del galeno.<\/p>\n\n\n\n<p><strong>Cahe conoci\u00f3 a Maradona por intermedio de quien fuera su primer representante, Jorge Cysterpiller. A partir de all\u00ed gener\u00f3 un fuerte v\u00ednculo con el Diez y estuvo a su lado en momentos dif\u00edciles de su vida. <\/strong>Episodios como la internaci\u00f3n de urgencia de Maradona en Punta del Este, en el a\u00f1o 2000, o la de cuatro a\u00f1os m\u00e1s tarde, en una cl\u00ednica porte\u00f1a por otro cuadro grave, encontraron a Cahe asisti\u00e9ndolo.<\/p>\n\n\n\n<p>M\u00e1s ac\u00e1 en el tiempo, cuando la resentida salud de Maradona deriv\u00f3 en su muerte, el 25 de noviembre de 2020, Cahe lanz\u00f3 duras cr\u00edticas contra los m\u00e9dicos que trataban al astro futbol\u00edstico. <strong>Fue durante una entrevista realizada en febrero de 2021, en la que tambi\u00e9n cont\u00f3 que no pod\u00eda ver a Maradona debido a que su entorno le cerr\u00f3 las puertas.<\/strong><\/p>\n\n\n\n<p><strong>\u201cCuando lo vi a Diego vivo en la Cl\u00ednica Olivos, pr\u00e1cticamente dopado y dormido, no pude hablar con la psiquiatra ni con el psic\u00f3logo. Se me cerraron las puertas. La \u00fanica vez que lo vi a Diego, lo vi dormido profundamente.<\/strong> Y el segundo d\u00eda que lo iba a ir a ver, ya se hab\u00eda producido el suicidio. Digo suicidio porque para m\u00ed fue un suicidio l\u00f3gico. Diego estaba cansado... para m\u00ed, todos estos acontecimientos de Diego fueron como consecuencia de un suicidio. Me acuerdo que una de las mujeres me dijo \u2018no quiere vivir m\u00e1s, est\u00e1 cansado de la vida. Ya hizo todo\u2019, y cuando sali\u00f3 de la habitaci\u00f3n se me comunic\u00f3 que Diego estaba muerto\u201d, fueron las duras palabras de Cahe en ese reportaje.<\/p>\n\n\n\n<p><strong>Antes del desenlace fatal, Cahe hab\u00eda sugerido volver a intentar con una internaci\u00f3n en Cuba, tal como hab\u00eda ocurrido a principios de siglo. Pero su propuesta no fue atendida por el c\u00edrculo \u00edntimo de Maradona.<\/strong><\/p>\n\n\n\n<p><strong>\u201cNo pude convencer a Luque de llevar a Diego a Cuba. Me cerr\u00f3 las puertas de la... Bueno, en realidad no era una cl\u00ednica ni nada, era un lugar donde Diego estaba pr\u00e1cticamente tirado.<\/strong> Lo importante de todo eso es que, en la poca conversaci\u00f3n que ten\u00edamos, yo le suger\u00ed a Luque que era importante e imprescindible llevarlo a un lugar adecuado previo, ac\u00e1 en la Capital, y despu\u00e9s s\u00ed dar el segundo paso y llevarlo a Cuba, donde ten\u00edamos todo a favor\u201d, agreg\u00f3.<\/p>\n\n\n\n<p>En otra entrevista, de las \u00faltimas que dio, Cahe hab\u00eda dicho que estar <strong>\u201cal lado de Diego durante 30 a\u00f1os fue una responsabilidad muy grande, porque Diego siempre confi\u00f3 en m\u00ed. Yo no fui a buscarlo, \u00e9l me eligi\u00f3 a m\u00ed. Yo trat\u00e9 de darle lo mejor con los mejores recursos m\u00e9dicos. Dios le dio a \u00e9l una magia en el f\u00fatbol y en su vida personal que yo conoc\u00ed muy sorprendente\u201d.<\/strong><\/p>\n\n\n\n<p>El especialista de la salud nacido en la localidad bonaerense de Santos Lugares tambi\u00e9n fue el m\u00e9dico personal de distintas estrellas del mundo del espect\u00e1culo y la m\u00fasica, como Cacho Casta\u00f1a, e incluso lleg\u00f3 a estar al lado de Susana Gim\u00e9nez sumado a otras figuras como China Zorrilla, Isabel Sarli y Gerardo Sofovich.<\/p>\n\n\n\n<p>Tiempo atr\u00e1s, Alfredo Cahe se hab\u00eda referido a sus v\u00ednculos con estos pacientes en una entrevista con La Prensa: <strong>\u201cNo es que uno quer\u00eda acaparar todo, sino que en las situaciones cr\u00edticas de la vida -por las que alguna vez hay que pasar porque todos nos enfermamos en alg\u00fan momento- ellos sent\u00edan que yo estaba ah\u00ed. <\/strong>Independientemente de que fuera o no mi especialidad, yo estaba ah\u00ed. Y estaba protegi\u00e9ndolos, tratando de curarlos, tratando de buscar lo mejor, a veces lo mejor est\u00e1 en colegas y yo busqu\u00e9 siempre lo mejor para ellos\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El profesional, que acompa\u00f1\u00f3 a Diego durante m\u00e1s de tres d\u00e9cadas, ten\u00eda 80 a\u00f1os. Alfredo Cahe, el hist\u00f3rico m\u00e9dico que acompa\u00f1\u00f3 a Diego Armando Maradona durante tres d\u00e9cadas y atendi\u00f3 a otros famosos durante su carrera, muri\u00f3 este viernes a los 80 a\u00f1os. \u201cCon profundo dolor despido a mi querido amigo Alfredo Cahe, reconocido por [&hellip;]<\/p>\n","protected":false},"author":49,"featured_media":415602,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_stopmodifiedupdate":false,"_modified_date":"","inline_featured_image":false,"spay_email":"","jetpack_publicize_message":""},"categories":[21,5],"tags":[],"jetpack_featured_media_url":"https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2024\/09\/diego-maradona-y-alfredo-cahe.jpg","jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts\/415601"}],"collection":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/users\/49"}],"replies":[{"embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/comments?post=415601"}],"version-history":[{"count":1,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts\/415601\/revisions"}],"predecessor-version":[{"id":415603,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts\/415601\/revisions\/415603"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/media\/415602"}],"wp:attachment":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/media?parent=415601"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/categories?post=415601"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/tags?post=415601"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}