{"id":415161,"date":"2024-09-06T10:55:13","date_gmt":"2024-09-06T13:55:13","guid":{"rendered":"https:\/\/notinor.com\/jujuy\/?p=415161"},"modified":"2024-09-06T10:55:18","modified_gmt":"2024-09-06T13:55:18","slug":"este-sabado-ejesa-realizara-tareas-de-mantenimiento-de-redes-electricas-en-b-san-pedrito-entre-avda-vespucio-burela-arizmendi-barcena","status":"publish","type":"post","link":"https:\/\/notinor.com\/jujuy\/este-sabado-ejesa-realizara-tareas-de-mantenimiento-de-redes-electricas-en-b-san-pedrito-entre-avda-vespucio-burela-arizmendi-barcena\/","title":{"rendered":"Este s\u00e1bado EJESA realizar\u00e1 tareas de  mantenimiento de redes el\u00e9ctricas en B\u00b0 San Pedrito (entre Avda. Vespucio, Burela, Arizmendi, Barcena)"},"content":{"rendered":"\n<p class=\"has-medium-font-size\"><strong><em>Informamos\u00a0que, con el objeto de\u00a0elevar la calidad de nuestro servicio,\u00a0se realizar\u00e1n tareas de\u00a0mantenimiento y renovaci\u00f3n\u00a0en las instalaciones de nuestro sistema.<\/em><\/strong><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img decoding=\"async\" loading=\"lazy\" width=\"840\" height=\"378\" src=\"https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2024\/09\/arismendi-840x378.jpg\" alt=\"\" class=\"wp-image-415163\" srcset=\"https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2024\/09\/arismendi-840x378.jpg 840w, https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2024\/09\/arismendi-660x297.jpg 660w, https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2024\/09\/arismendi-768x346.jpg 768w, https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2024\/09\/arismendi-750x338.jpg 750w, https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2024\/09\/arismendi.jpg 946w\" sizes=\"(max-width: 840px) 100vw, 840px\" \/><\/figure><\/div>\n\n\n<p>Con este fin, ser\u00e1 necesario efectuar una&nbsp;interrupci\u00f3n programada en las siguientes zonas y horarios:<\/p>\n\n\n\n<p>\ud83d\udcccSAN SALVADOR DE JUJUY<\/p>\n\n\n\n<p>\ud83d\uddd3\ufe0f S\u00c1BADO 07\/09\/2024&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<p>\ud83d\udd52&nbsp;De 08:00 a 12:00 Hs aprox.<\/p>\n\n\n\n<p>Zonas: B\u00b0 San Pedrito (entre Avda. Vespucio, Burela, Arizmendi, Barcena) y zonas aleda\u00f1as.<\/p>\n\n\n\n<p>Agradecemos tomar las precauciones necesarias durante la duraci\u00f3n de dicha interrupci\u00f3n a fin de evitar mayores inconvenientes.<\/p>\n\n\n\n<p>Por consultas y\/o requerimientos te recordamos nuestros canales oficiales de contacto disponibles las 24hs. A trav\u00e9s de este link:&nbsp;<a href=\"https:\/\/linktr.ee\/ejesa\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/linktr.ee\/ejesa<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Informamos\u00a0que, con el objeto de\u00a0elevar la calidad de nuestro servicio,\u00a0se realizar\u00e1n tareas de\u00a0mantenimiento y renovaci\u00f3n\u00a0en las instalaciones de nuestro sistema. Con este fin, ser\u00e1 necesario efectuar una&nbsp;interrupci\u00f3n programada en las siguientes zonas y horarios: \ud83d\udcccSAN SALVADOR DE JUJUY \ud83d\uddd3\ufe0f S\u00c1BADO 07\/09\/2024&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; \ud83d\udd52&nbsp;De 08:00 a 12:00 Hs aprox. Zonas: B\u00b0 San Pedrito (entre Avda. Vespucio, Burela, [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":415162,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_stopmodifiedupdate":false,"_modified_date":"","inline_featured_image":false,"spay_email":"","jetpack_publicize_message":""},"categories":[514],"tags":[],"jetpack_featured_media_url":"https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2024\/09\/AV-VESPUCIO-Y-BURELA.jpg","jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts\/415161"}],"collection":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/comments?post=415161"}],"version-history":[{"count":1,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts\/415161\/revisions"}],"predecessor-version":[{"id":415164,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts\/415161\/revisions\/415164"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/media\/415162"}],"wp:attachment":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/media?parent=415161"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/categories?post=415161"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/tags?post=415161"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}