{"id":415087,"date":"2024-09-05T09:39:24","date_gmt":"2024-09-05T12:39:24","guid":{"rendered":"https:\/\/notinor.com\/jujuy\/?p=415087"},"modified":"2024-09-05T09:39:26","modified_gmt":"2024-09-05T12:39:26","slug":"ejesa-realizara-tareas-de-mejora-y-mantenimiento-de-redes-electricas-este-viernes-en-barrios-de-el-carmen","status":"publish","type":"post","link":"https:\/\/notinor.com\/jujuy\/ejesa-realizara-tareas-de-mejora-y-mantenimiento-de-redes-electricas-este-viernes-en-barrios-de-el-carmen\/","title":{"rendered":"EJESA realizar\u00e1 tareas de mejora y mantenimiento de redes el\u00e9ctricas este viernes en barrios de El Carmen"},"content":{"rendered":"\n<p class=\"has-medium-font-size\"><strong><em>Informamos\u00a0que, con el objeto de\u00a0elevar la calidad de nuestro servicio,\u00a0se realizar\u00e1n tareas de\u00a0mantenimiento y renovaci\u00f3n\u00a0en las instalaciones de nuestro sistema.<\/em><\/strong><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2023\/09\/El-Carmen.jpg\" alt=\"\" class=\"wp-image-389844\" width=\"750\" height=\"439\"\/><\/figure><\/div>\n\n\n<p>Con este fin, ser\u00e1 necesario efectuar una&nbsp;interrupci\u00f3n programada en las siguientes zonas y horarios:<\/p>\n\n\n\n<p>\ud83d\udcccEL CARMEN<\/p>\n\n\n\n<p>\ud83d\uddd3\ufe0f VIERNES 06\/09\/2024&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<p>\ud83d\udd52&nbsp;De 09:00 a 14:00 Hs aprox.<\/p>\n\n\n\n<p>Zonas: B\u00b0 25 de Mayo, B\u00b0 San Juan, B\u00b0 Centro (entre Avda. Centenario, Arenas, Gral. Paz, Sarmiento) y zonas aleda\u00f1as.<\/p>\n\n\n\n<p>Agradecemos tomar las precauciones necesarias durante la duraci\u00f3n de dicha interrupci\u00f3n a fin de evitar mayores inconvenientes.<\/p>\n\n\n\n<p>Por consultas y\/o requerimientos te recordamos nuestros canales oficiales de contacto disponibles las 24hs. A trav\u00e9s de este link:&nbsp;<a href=\"https:\/\/linktr.ee\/ejesa\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/linktr.ee\/ejesa<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Informamos\u00a0que, con el objeto de\u00a0elevar la calidad de nuestro servicio,\u00a0se realizar\u00e1n tareas de\u00a0mantenimiento y renovaci\u00f3n\u00a0en las instalaciones de nuestro sistema. Con este fin, ser\u00e1 necesario efectuar una&nbsp;interrupci\u00f3n programada en las siguientes zonas y horarios: \ud83d\udcccEL CARMEN \ud83d\uddd3\ufe0f VIERNES 06\/09\/2024&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; \ud83d\udd52&nbsp;De 09:00 a 14:00 Hs aprox. Zonas: B\u00b0 25 de Mayo, B\u00b0 San Juan, B\u00b0 Centro [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":389844,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_stopmodifiedupdate":false,"_modified_date":"","inline_featured_image":false,"spay_email":"","jetpack_publicize_message":""},"categories":[4],"tags":[],"jetpack_featured_media_url":"https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2023\/09\/El-Carmen.jpg","jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts\/415087"}],"collection":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/comments?post=415087"}],"version-history":[{"count":1,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts\/415087\/revisions"}],"predecessor-version":[{"id":415088,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts\/415087\/revisions\/415088"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/media\/389844"}],"wp:attachment":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/media?parent=415087"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/categories?post=415087"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/tags?post=415087"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}