{"id":413658,"date":"2024-08-12T21:50:00","date_gmt":"2024-08-13T00:50:00","guid":{"rendered":"https:\/\/notinor.com\/jujuy\/?p=413658"},"modified":"2024-08-12T09:50:31","modified_gmt":"2024-08-12T09:50:31","slug":"la-municipalidad-brindara-un-taller-de-capacitacion-tributaria","status":"publish","type":"post","link":"https:\/\/notinor.com\/jujuy\/la-municipalidad-brindara-un-taller-de-capacitacion-tributaria\/","title":{"rendered":"La Municipalidad brindar\u00e1 un taller de Capacitaci\u00f3n Tributaria"},"content":{"rendered":"\n<p class=\"has-medium-font-size\"><strong><em>La Municipalidad de San Salvador de Jujuy, a trav\u00e9s de la Direcci\u00f3n de Oficios y Empleo, dependiente de la Secretar\u00eda de Planificaci\u00f3n y Ambiente, informa a la comunidad que se encuentran abiertas las inscripciones del Taller de Capacitaci\u00f3n Tributaria, a trav\u00e9s del cual se brindar\u00e1n nociones sobre el manejo de las herramientas inform\u00e1ticas disponibles en la Administraci\u00f3n Federal de Ingresos P\u00fablicos. La propuesta, que iniciar\u00e1 el pr\u00f3ximo 4 de septiembre, prev\u00e9 tres jornadas de trabajo que se desarrollar\u00e1n en el Mercado Municipal de Avenida Almirante Brown, y estar\u00e1n a cargo de la CPN, Liliana Morales.<\/em><\/strong><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img decoding=\"async\" loading=\"lazy\" width=\"480\" height=\"480\" src=\"https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2024\/08\/CAPACITACION-TRIBUTARIA-480x480.jpeg\" alt=\"\" class=\"wp-image-413660\" srcset=\"https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2024\/08\/CAPACITACION-TRIBUTARIA-480x480.jpeg 480w, https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2024\/08\/CAPACITACION-TRIBUTARIA-365x365.jpeg 365w, https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2024\/08\/CAPACITACION-TRIBUTARIA-768x768.jpeg 768w, https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2024\/08\/CAPACITACION-TRIBUTARIA-75x75.jpeg 75w, https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2024\/08\/CAPACITACION-TRIBUTARIA-750x750.jpeg 750w, https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2024\/08\/CAPACITACION-TRIBUTARIA.jpeg 1024w\" sizes=\"(max-width: 480px) 100vw, 480px\" \/><\/figure><\/div>\n\n\n<p>En el marco de la agenda 2030 para el logro de los Objetivos de Desarrollo Sostenible (ODS), la Secretar\u00eda de Planificaci\u00f3n y Ambiente de la comuna capitalina brindar\u00e1 una instancia de capacitaci\u00f3n que apunta a promover: el crecimiento econ\u00f3mico sostenido, inclusivo y sostenible; el empleo pleno y productivo, y el trabajo decente para todos.<\/p>\n\n\n\n<p>La actividad est\u00e1 destinada, en lo particular, a emprendedores que gestionaron proyectos del Programa de Empleo Independiente (PEI); ciudadanas\/os que gestionan un proyecto, o en espera de aprobaci\u00f3n, y contribuyentes adheridos al R\u00e9gimen Simplificado, en cualquiera de las opciones previstas en el mismo.<\/p>\n\n\n\n<p>En los fundamentos de la propuesta se destaca, entre otros aspectos, que para lograr un desarrollo econ\u00f3mico sostenible es necesario que la sociedad genere las condiciones para que las personas accedan a empleos de calidad y se estimule la econom\u00eda sin da\u00f1ar el medio ambiente. Tambi\u00e9n se aboga por la promoci\u00f3n de oportunidades laborales con condiciones de trabajo decentes para toda la poblaci\u00f3n en edad de trabajar.<\/p>\n\n\n\n<p>Con acuerdo a ello, se procura que los participantes del taller tomen conciencia de la importancia del sentido social de los tributos, como fuente de financiamiento de \u201clo p\u00fablico\u201d. A la vez, que adquieran informaci\u00f3n de los beneficios del trabajo formal independiente, a trav\u00e9s de las opciones previstas por el R\u00e9gimen Simplificado para Peque\u00f1os Contribuyentes, y que aprendan a usar las herramientas disponibles en la p\u00e1gina web de la Administraci\u00f3n Federal de Ingresos P\u00fablico, para efectuar diversos tr\u00e1mites vinculados con el R\u00e9gimen Simplificado.<\/p>\n\n\n\n<p>Desde la Direcci\u00f3n de Oficios y Empleo se informa que los interesados podr\u00e1n inscribirse de 8 a 18 horas en el Mercado de Abasto, Rivadavia N\u00b0 70, del barrio Almirante Brown. A la vez, se precisa que el Taller iniciar\u00e1 el 4 de septiembre de 2024, y continuar\u00e1 los d\u00edas 11 y 18, de 10 a 11 horas, en el Sal\u00f3n de Inform\u00e1tica ubicado en el primer piso del Mercado Municipal. Finalmente se menciona que los interesados deber\u00e1n asistir con material para tomar apuntes\/internet; disponer CUIT y Clave fiscal para poder practicar (Opcional), y contar con comprensi\u00f3n lectora.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Municipalidad de San Salvador de Jujuy, a trav\u00e9s de la Direcci\u00f3n de Oficios y Empleo, dependiente de la Secretar\u00eda de Planificaci\u00f3n y Ambiente, informa a la comunidad que se encuentran abiertas las inscripciones del Taller de Capacitaci\u00f3n Tributaria, a trav\u00e9s del cual se brindar\u00e1n nociones sobre el manejo de las herramientas inform\u00e1ticas disponibles en [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":413659,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_stopmodifiedupdate":false,"_modified_date":"","inline_featured_image":false,"spay_email":"","jetpack_publicize_message":""},"categories":[13],"tags":[],"jetpack_featured_media_url":"https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2024\/08\/CAPACITACION-TRIBUTARIA.jpg","jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts\/413658"}],"collection":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/comments?post=413658"}],"version-history":[{"count":1,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts\/413658\/revisions"}],"predecessor-version":[{"id":413661,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts\/413658\/revisions\/413661"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/media\/413659"}],"wp:attachment":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/media?parent=413658"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/categories?post=413658"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/tags?post=413658"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}