{"id":413604,"date":"2024-08-12T09:59:55","date_gmt":"2024-08-12T12:59:55","guid":{"rendered":"https:\/\/notinor.com\/jujuy\/?p=413604"},"modified":"2024-08-12T09:59:56","modified_gmt":"2024-08-12T12:59:56","slug":"sadir-acompano-a-productores-de-la-agricultura-familiar","status":"publish","type":"post","link":"https:\/\/notinor.com\/jujuy\/sadir-acompano-a-productores-de-la-agricultura-familiar\/","title":{"rendered":"Sadir acompa\u00f1\u00f3 a productores de la agricultura familiar"},"content":{"rendered":"\n<p class=\"has-medium-font-size\"><strong><em>En el predio de Ciudad Cultural, se concret\u00f3 el 6\u00b0 Encuentro Provincial de Ferias Campesinas, evento que posibilit\u00f3 que productores de las cuatro regiones logren comercializar y difundir su experiencia de trabajo. El gobernador Carlos Sadir recorri\u00f3 la exposici\u00f3n en su \u00faltima jornada.<\/em><\/strong><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/media.prensa.jujuy.gob.ar\/p\/a22877e4fd45da261bbff6cf5134e7ee\/adjuntos\/301\/imagenes\/000\/399\/0000399753\/1200x0\/smart\/sadir-acompano-productores-la-agricultura-familiar.jpeg\" alt=\"Sadir acompa\u00f1\u00f3 a productores de la agricultura familiar\" title=\"Sadir acompa\u00f1\u00f3 a productores de la agricultura familiar\"\/><\/figure><\/div>\n\n\n<p>Durante su visita, el mandatario se interioriz\u00f3 sobre la muestra que reuni\u00f3 a m\u00e1s de 200 productores y emprendedores de las zonas de la Quebrada, Puna, Valles y Yungas, con la finalidad de favorecer a la econom\u00eda popular y acercar a los consumidores productos de la agricultura regional local.<a href=\"https:\/\/media.prensa.jujuy.gob.ar\/p\/a22877e4fd45da261bbff6cf5134e7ee\/adjuntos\/301\/imagenes\/000\/399\/0000399753\/1200x0\/smart\/sadir-acompano-productores-la-agricultura-familiar.jpeg\"><\/a><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/media.prensa.jujuy.gob.ar\/p\/0574eccabb4b0f37cef47292d971b560\/adjuntos\/301\/imagenes\/000\/399\/0000399754\/1200x0\/smart\/sadir-acompano-productores-la-agricultura-familiar.jpeg\" alt=\"Sadir acompa\u00f1\u00f3 a productores de la agricultura familiar\" title=\"Sadir acompa\u00f1\u00f3 a productores de la agricultura familiar\"\/><\/figure><\/div>\n\n\n<p>Luego de dialogar con los productores, el gobernador expres\u00f3 que \u201cac\u00e1 hay varios que trabajan la tierra y lograron vender sus productos de forma directa, con buena aceptaci\u00f3n del p\u00fablico\u201d.<a href=\"https:\/\/media.prensa.jujuy.gob.ar\/p\/0574eccabb4b0f37cef47292d971b560\/adjuntos\/301\/imagenes\/000\/399\/0000399754\/1200x0\/smart\/sadir-acompano-productores-la-agricultura-familiar.jpeg\"><\/a><\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/media.prensa.jujuy.gob.ar\/p\/cb56b9bd2abca50ccf35de1be1a7605a\/adjuntos\/301\/imagenes\/000\/399\/0000399755\/1200x0\/smart\/sadir-acompano-productores-la-agricultura-familiar.jpeg\" alt=\"Sadir acompa\u00f1\u00f3 a productores de la agricultura familiar\" title=\"Sadir acompa\u00f1\u00f3 a productores de la agricultura familiar\"\/><\/figure>\n\n\n\n<p>Resalt\u00f3 que \u201chay un pedido de todos los productores y emprendedores de seguir replicando esta feria\u201d y a\u00f1adi\u00f3 que \u201cla idea es acompa\u00f1arlos y que puedan estar una vez al mes\u201d.<a href=\"https:\/\/media.prensa.jujuy.gob.ar\/p\/cb56b9bd2abca50ccf35de1be1a7605a\/adjuntos\/301\/imagenes\/000\/399\/0000399755\/1200x0\/smart\/sadir-acompano-productores-la-agricultura-familiar.jpeg\"><\/a><\/p>\n\n\n\n<p>Continuando, apunt\u00f3 que \u201caqu\u00ed hay productores de lugares muy alejados de San Salvador. Hay gente de Susques, Palca de Aparzo, Maimar\u00e1 y Humahuaca, entre otros\u201d.&nbsp;<\/p>\n\n\n\n<p>\u201cAqu\u00ed se ven excelentes productos ni hablar de los precios que son accesibles\u201d, enfatiz\u00f3.\u00a0<\/p>\n\n\n\n<p>Por su parte, Inocencia Zapana, integrante del Movimiento Campesino Ind\u00edgena Pucar\u00e1, coment\u00f3 que \u201cgracias a la ayuda del gobierno hicimos esta feria\u201d y subray\u00f3 que \u201cvendimos bien nuestros productos estos d\u00edas, por eso la idea es que se sumen m\u00e1s productores\u201d.&nbsp;<\/p>\n\n\n\n<p>Cabe indicar que, en esta edici\u00f3n, el encuentro cont\u00f3 con la participaci\u00f3n de 248 productores de cultivo y artesanos de tejido, bordado y cuero, entre otros rubros.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En el predio de Ciudad Cultural, se concret\u00f3 el 6\u00b0 Encuentro Provincial de Ferias Campesinas, evento que posibilit\u00f3 que productores de las cuatro regiones logren comercializar y difundir su experiencia de trabajo. El gobernador Carlos Sadir recorri\u00f3 la exposici\u00f3n en su \u00faltima jornada. Durante su visita, el mandatario se interioriz\u00f3 sobre la muestra que reuni\u00f3 [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":413606,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_stopmodifiedupdate":false,"_modified_date":"","inline_featured_image":false,"spay_email":"","jetpack_publicize_message":""},"categories":[2],"tags":[],"jetpack_featured_media_url":"https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2024\/08\/sadir.webp","jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts\/413604"}],"collection":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/comments?post=413604"}],"version-history":[{"count":1,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts\/413604\/revisions"}],"predecessor-version":[{"id":413607,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts\/413604\/revisions\/413607"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/media\/413606"}],"wp:attachment":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/media?parent=413604"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/categories?post=413604"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/tags?post=413604"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}