{"id":413376,"date":"2024-08-07T21:36:05","date_gmt":"2024-08-08T00:36:05","guid":{"rendered":"https:\/\/notinor.com\/jujuy\/?p=413376"},"modified":"2024-08-07T21:36:07","modified_gmt":"2024-08-08T00:36:07","slug":"sadir-otorgo-el-ascenso-a-2-417-efectivos-de-la-policia","status":"publish","type":"post","link":"https:\/\/notinor.com\/jujuy\/sadir-otorgo-el-ascenso-a-2-417-efectivos-de-la-policia\/","title":{"rendered":"Sadir otorg\u00f3 el ascenso a 2.417 efectivos de la Polic\u00eda"},"content":{"rendered":"\n<p class=\"has-medium-font-size\"><strong><em>El mandatario firm\u00f3 el decreto por el cual dispuso el ascenso de 2.417 efectivos de la Polic\u00eda de la Provincia, por lo que 358 efectivos correspondientes al personal superior y 2059 subalternos escalaron un grado superior inmediato.<\/em><\/strong><\/p>\n\n\n\n<p><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" loading=\"lazy\" width=\"800\" height=\"450\" src=\"https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2024\/08\/carlos-sadir-1.jpg\" alt=\"\" class=\"wp-image-413377\" srcset=\"https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2024\/08\/carlos-sadir-1.jpg 800w, https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2024\/08\/carlos-sadir-1-649x365.jpg 649w, https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2024\/08\/carlos-sadir-1-500x280.jpg 500w, https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2024\/08\/carlos-sadir-1-768x432.jpg 768w, https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2024\/08\/carlos-sadir-1-750x422.jpg 750w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure><\/div>\n\n\n<p><\/p>\n\n\n\n<p>Carlos Sadir felicit\u00f3 a los polic\u00edas promocionados, que de acuerdo al m\u00e9rito y a la legislaci\u00f3n vigente les corresponde el ascenso. <strong>\u201cM\u00e1s de 2.400 polic\u00edas se van a ver beneficiados, a ellos les quiero mandar un fuerte abrazo\u201d,<\/strong> expres\u00f3.<\/p>\n\n\n\n<p>Cabe destacar, que la nominaci\u00f3n de los efectivos para el ascenso corresponde tanto al presente ejercicio, como tambi\u00e9n a promociones retroactivas al per\u00edodo 2015-2023.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El mandatario firm\u00f3 el decreto por el cual dispuso el ascenso de 2.417 efectivos de la Polic\u00eda de la Provincia, por lo que 358 efectivos correspondientes al personal superior y 2059 subalternos escalaron un grado superior inmediato. Carlos Sadir felicit\u00f3 a los polic\u00edas promocionados, que de acuerdo al m\u00e9rito y a la legislaci\u00f3n vigente les [&hellip;]<\/p>\n","protected":false},"author":49,"featured_media":413377,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_stopmodifiedupdate":false,"_modified_date":"","inline_featured_image":false,"spay_email":"","jetpack_publicize_message":""},"categories":[2,514,3],"tags":[],"jetpack_featured_media_url":"https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2024\/08\/carlos-sadir-1.jpg","jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts\/413376"}],"collection":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/users\/49"}],"replies":[{"embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/comments?post=413376"}],"version-history":[{"count":1,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts\/413376\/revisions"}],"predecessor-version":[{"id":413378,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts\/413376\/revisions\/413378"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/media\/413377"}],"wp:attachment":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/media?parent=413376"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/categories?post=413376"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/tags?post=413376"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}