{"id":413321,"date":"2024-08-07T09:03:29","date_gmt":"2024-08-07T12:03:29","guid":{"rendered":"https:\/\/notinor.com\/jujuy\/?p=413321"},"modified":"2024-08-07T09:03:31","modified_gmt":"2024-08-07T12:03:31","slug":"sadir-participo-de-la-entrega-de-los-premios-san-salvador","status":"publish","type":"post","link":"https:\/\/notinor.com\/jujuy\/sadir-participo-de-la-entrega-de-los-premios-san-salvador\/","title":{"rendered":"Sadir particip\u00f3 de la entrega de los Premios San Salvador"},"content":{"rendered":"\n<p class=\"has-medium-font-size\"><strong><em>En una nueva edici\u00f3n de los Premios San Salvador 2024, el Gobernador Carlos Sadir acompa\u00f1o al Intendente Ra\u00fal Jorge en la entrega de galardones hacia vecinos notables, profesionales e instituciones distinguidos por dejar impronta en la comunidad.<\/em><\/strong><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/media.prensa.jujuy.gob.ar\/p\/6e4d19ccdb0d7d931b6c7ce0248e2797\/adjuntos\/301\/imagenes\/000\/399\/0000399564\/1200x0\/smart\/060824-sadir-entrega-premios-san-salvador-3jpg.jpg\" alt=\"Sadir particip\u00f3 de la entrega de los Premios San Salvador\" title=\"Sadir particip\u00f3 de la entrega de los Premios San Salvador\"\/><figcaption class=\"wp-element-caption\">Premios San Salvador<\/figcaption><\/figure><\/div>\n\n\n<p>El evento se desarroll\u00f3 en el Centro Cultural \u00c9xodo Juje\u00f1o y cont\u00f3 con la participaci\u00f3n del Ministro de Gobierno, Justicia, Derechos Humanos y Trabajo, <strong>Normando Alvarez Garc\u00eda<\/strong> y el Secretario de Cultura de la Provincia, <strong>Jos\u00e9 Rodriguez B\u00e1rcena<\/strong>.<a href=\"https:\/\/media.prensa.jujuy.gob.ar\/p\/6e4d19ccdb0d7d931b6c7ce0248e2797\/adjuntos\/301\/imagenes\/000\/399\/0000399564\/1200x0\/smart\/060824-sadir-entrega-premios-san-salvador-3jpg.jpg\"><\/a><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/media.prensa.jujuy.gob.ar\/p\/104ed60eee2f119818f3e382ec7b2fea\/adjuntos\/301\/imagenes\/000\/399\/0000399565\/1200x0\/smart\/060824-sadir-entrega-premios-san-salvador-4jpg.jpg\" alt=\"Sadir particip\u00f3 de la entrega de los Premios San Salvador\" title=\"Sadir particip\u00f3 de la entrega de los Premios San Salvador\"\/><\/figure><\/div>\n\n\n<p>Luego de la ceremonia el primer mandatario se\u00f1alo que \u201ceste es un evento importante que viene repitiendo la municipalidad desde hace muchos a\u00f1os y es una gran oportunidad para valorar la actividad en distintos rubros que hacen los juje\u00f1os por la provincia d\u00eda a d\u00eda. A veces hay personas que trabajan en el anonimato y es importante destacarlos\u201d.<a href=\"https:\/\/media.prensa.jujuy.gob.ar\/p\/104ed60eee2f119818f3e382ec7b2fea\/adjuntos\/301\/imagenes\/000\/399\/0000399565\/1200x0\/smart\/060824-sadir-entrega-premios-san-salvador-4jpg.jpg\"><\/a><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/media.prensa.jujuy.gob.ar\/p\/fae88e892f9ae4ac39aa4980ed3e29b9\/adjuntos\/301\/imagenes\/000\/399\/0000399566\/1200x0\/smart\/060824-sadir-entrega-premios-san-salvador-5jpg.jpg\" alt=\"Sadir particip\u00f3 de la entrega de los Premios San Salvador\" title=\"Sadir particip\u00f3 de la entrega de los Premios San Salvador\"\/><\/figure><\/div>\n\n\n<p>Por su parte, el intendente expres\u00f3 \"es un d\u00eda tan especial, porque estamos destacando el trabajo social, humanitaria y vocaci\u00f3n de ciudadan\u00eda a nuestra comunidad. Es un honor refutar con este premio San Salvador que viene desde el a\u00f1o 1993, donde Hugo Cid Conde lo puso en vigencia, y cuando asum\u00ed como intendente entend\u00ed que deb\u00eda seguir consolid\u00e1ndola\u201d.<a href=\"https:\/\/media.prensa.jujuy.gob.ar\/p\/fae88e892f9ae4ac39aa4980ed3e29b9\/adjuntos\/301\/imagenes\/000\/399\/0000399566\/1200x0\/smart\/060824-sadir-entrega-premios-san-salvador-5jpg.jpg\"><\/a><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/media.prensa.jujuy.gob.ar\/p\/99d0867c1422bb62632d4c916bca9e9f\/adjuntos\/301\/imagenes\/000\/399\/0000399567\/1200x0\/smart\/060824-sadir-entrega-premios-san-salvador-7jpg.jpg\" alt=\"Sadir particip\u00f3 de la entrega de los Premios San Salvador\" title=\"Sadir particip\u00f3 de la entrega de los Premios San Salvador\"\/><\/figure><\/div>\n\n\n<p>Finalmente, el intendente resalt\u00f3 que el evento genera un ambiente c\u00e1lido entre amigos, familia y grupo humano que viene a acompa\u00f1ar a cada galardonado en seguir apostando a una provincia m\u00e1s participativa y amigable.\u00a0<a href=\"https:\/\/media.prensa.jujuy.gob.ar\/p\/99d0867c1422bb62632d4c916bca9e9f\/adjuntos\/301\/imagenes\/000\/399\/0000399567\/1200x0\/smart\/060824-sadir-entrega-premios-san-salvador-7jpg.jpg\"><\/a><\/p>\n\n\n\n<p>Cabe destacar que fueron un total de 25 los galardonados en esta edici\u00f3n, quienes recibieron estatuillas por su labor transcendente, trayectoria y por enarbolan el crecimiento de la sociedad.&nbsp;<\/p>\n\n\n\n<p>Tambi\u00e9n estuvieron presentes, el Presidente de la Suprema Corte de Justicia, doctor Ekel Meyer; el intendente de El Carmen, V\u00edctor Hugo Gonz\u00e1lez; el presidente del Concejo Deliberante de San Salvador de Jujuy; Lisandro Aguiar: Autoridades municipales, diputados provinciales, entre otros.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/media.prensa.jujuy.gob.ar\/p\/762b945a9093e313bd255749e6ae5d4b\/adjuntos\/301\/imagenes\/000\/399\/0000399563\/1200x0\/smart\/060824-sadir-entrega-premios-san-salvador-1jpg.jpg\" alt=\"\" title=\"\"\/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>En una nueva edici\u00f3n de los Premios San Salvador 2024, el Gobernador Carlos Sadir acompa\u00f1o al Intendente Ra\u00fal Jorge en la entrega de galardones hacia vecinos notables, profesionales e instituciones distinguidos por dejar impronta en la comunidad. El evento se desarroll\u00f3 en el Centro Cultural \u00c9xodo Juje\u00f1o y cont\u00f3 con la participaci\u00f3n del Ministro de [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":413322,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_stopmodifiedupdate":false,"_modified_date":"","inline_featured_image":false,"spay_email":"","jetpack_publicize_message":""},"categories":[2],"tags":[],"jetpack_featured_media_url":"https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2024\/08\/premios.jpg","jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts\/413321"}],"collection":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/comments?post=413321"}],"version-history":[{"count":1,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts\/413321\/revisions"}],"predecessor-version":[{"id":413323,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts\/413321\/revisions\/413323"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/media\/413322"}],"wp:attachment":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/media?parent=413321"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/categories?post=413321"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/tags?post=413321"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}