{"id":328523,"date":"2022-02-14T22:08:00","date_gmt":"2022-02-15T01:08:00","guid":{"rendered":"https:\/\/notinor.com\/jujuy\/?p=328523"},"modified":"2022-02-14T22:08:04","modified_gmt":"2022-02-15T01:08:04","slug":"jujuy-fallecieron-3-personas-y-confirmaron-115-nuevos-casos-de-coronavirus","status":"publish","type":"post","link":"https:\/\/notinor.com\/jujuy\/jujuy-fallecieron-3-personas-y-confirmaron-115-nuevos-casos-de-coronavirus\/","title":{"rendered":"Jujuy: fallecieron 3 personas y confirmaron 115 nuevos casos de coronavirus"},"content":{"rendered":"\n<p>Las v\u00edctimas son dos hombres y una mujer. <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" loading=\"lazy\" width=\"800\" height=\"450\" src=\"https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2022\/02\/coronavirus-jujuy.jpg\" alt=\"\" class=\"wp-image-327653\" srcset=\"https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2022\/02\/coronavirus-jujuy.jpg 800w, https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2022\/02\/coronavirus-jujuy-649x365.jpg 649w, https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2022\/02\/coronavirus-jujuy-500x280.jpg 500w, https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2022\/02\/coronavirus-jujuy-768x432.jpg 768w, https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2022\/02\/coronavirus-jujuy-750x422.jpg 750w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<p>Desde la Subdirecci\u00f3n de Epidemiolog\u00eda informaron en su reporte diario que <strong>hoy se confirmaron 115 nuevos casos de COVID-19 y 3 fallecimientos en Jujuy. Adem\u00e1s, recibieron el alta m\u00e9dica 143 pacientes.<\/strong><\/p>\n\n\n\n<p><strong>Detalle de casos positivos seg\u00fan localidad:<\/strong><\/p>\n\n\n\n<p>SAN SALVADOR DE JUJUY 39<br>LIBERTADOR GENERAL SAN MART\u00cdN 37<br>SAN PEDRO 17<br>PALPAL\u00c1 6<br>CALILEGUA 5<br>LA ESPERANZA 3<br>PERICO 2<br>MONTERRICO 2<br>LA QUIACA 1<br>LA MENDIETA 1<br>FRAILE PINTADO 1<br>EL CARMEN 1<\/p>\n\n\n\n<p><strong>Se notific\u00f3 3 fallecimientos por Covid-19: <\/strong>dos hombres y una mujer entre 61 y 91 a\u00f1os de edad. Cabe aclarar que los fallecimientos son reportados e informados por el Registro Civil de la Provincia de Jujuy y corresponden a d\u00edas anteriores.<\/p>\n\n\n\n<p><strong>Estado de situaci\u00f3n desde el inicio de la pandemia:<\/strong><\/p>\n\n\n\n<p>Hasta el momento se realizaron 372.028 tests en toda la Provincia, arrojando un total de 104.106 casos positivos. Se recuperaron de la enfermedad 101.397. Fallecieron 1.691 personas.<\/p>\n\n\n\n<h4 class=\"has-text-align-center\"><strong><em>Ante el m\u00ednimo s\u00edntoma que tengas, quedate en casa y consult\u00e1 con tu m\u00e9dico de cabecera o pod\u00e9s llamar al 0800-888-4767 las 24 horas o al 388 -4310494 (COE) de 08.00 a 20.00 hs.<\/em><\/strong><\/h4>\n","protected":false},"excerpt":{"rendered":"<p>Las v\u00edctimas son dos hombres y una mujer. Desde la Subdirecci\u00f3n de Epidemiolog\u00eda informaron en su reporte diario que hoy se confirmaron 115 nuevos casos de COVID-19 y 3 fallecimientos en Jujuy. Adem\u00e1s, recibieron el alta m\u00e9dica 143 pacientes. Detalle de casos positivos seg\u00fan localidad: SAN SALVADOR DE JUJUY 39LIBERTADOR GENERAL SAN MART\u00cdN 37SAN PEDRO [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":327653,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_stopmodifiedupdate":false,"_modified_date":"","inline_featured_image":false,"spay_email":"","jetpack_publicize_message":""},"categories":[2],"tags":[],"jetpack_featured_media_url":"https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2022\/02\/coronavirus-jujuy.jpg","jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts\/328523"}],"collection":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/comments?post=328523"}],"version-history":[{"count":1,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts\/328523\/revisions"}],"predecessor-version":[{"id":328524,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts\/328523\/revisions\/328524"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/media\/327653"}],"wp:attachment":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/media?parent=328523"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/categories?post=328523"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/tags?post=328523"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}