{"id":315222,"date":"2021-10-22T09:56:14","date_gmt":"2021-10-22T12:56:14","guid":{"rendered":"https:\/\/notinor.com\/jujuy\/?p=315222"},"modified":"2021-10-22T09:56:19","modified_gmt":"2021-10-22T12:56:19","slug":"argentina-reafirmo-en-la-onu-su-posicion-sobre-malvinas-y-cosecho-respaldo-internacional","status":"publish","type":"post","link":"https:\/\/notinor.com\/jujuy\/argentina-reafirmo-en-la-onu-su-posicion-sobre-malvinas-y-cosecho-respaldo-internacional\/","title":{"rendered":"Argentina reafirm\u00f3 en la ONU su posici\u00f3n sobre Malvinas y cosech\u00f3 respaldo internacional"},"content":{"rendered":"\n<p>Fue a trav\u00e9s de la embajadora Mar\u00eda del Carmen Squeff, quien apoy\u00f3 la postura nacional y\u00a0reiter\u00f3 la disposici\u00f3n de Argentina \u201ca contribuir a la descolonizaci\u00f3n del territorio\", al mismo tiempo, se\u00f1al\u00f3 que existe\u00a0\u201cuna presencia militar desproporcionada en el Atl\u00e1ntico Sur\", ya denunciadas por el pa\u00eds.<\/p>\n\n\n\n<figure class=\"wp-block-image is-resized\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.telam.com.ar\/advf\/imagenes\/2018\/01\/5a4e00048f4d4_1004x565.jpg\" alt=\"La representante permanente de la Argentina ante las Naciones Unidas, la embajadora Mar\u00eda del Carmen Squeff, reafirm\u00f3 hoy ante los miembros de la ONU la posici\u00f3n nacional sobre la cuesti\u00f3n de las Islas Malvinas .\" width=\"1179\" height=\"663\"\/><\/figure>\n\n\n\n<p>La&nbsp;<strong>representante permanente de la Argentina ante las Naciones Unidas, la embajadora Mar\u00eda del Carmen Squeff<\/strong>, reafirm\u00f3 este jueves ante los miembros de la ONU la posici\u00f3n nacional sobre la cuesti\u00f3n de las Islas Malvinas e inst\u00f3 a Gran Breta\u00f1a a iniciar las negociaciones \u201cpara encontrar una soluci\u00f3n pac\u00edfica y definitiva\u201d, por lo que obtuvo un gran respaldo internacional.<\/p>\n\n\n\n<p>En el marco del inicio del Debate General de la Comisi\u00f3n de Pol\u00edtica Especial y Descolonizaci\u00f3n de la Asamblea General de las Naciones Unidas correspondiente a la Cuarta Comisi\u00f3n, la embajadora Squeff desarroll\u00f3 los argumentos que sustentan la posici\u00f3n nacional, seg\u00fan se inform\u00f3 en un comunicado difundido por Canciller\u00eda.<\/p>\n\n\n\n<p>La diplom\u00e1tica reiter\u00f3<strong>&nbsp;la disposici\u00f3n de Argentina \u201ca contribuir a la descolonizaci\u00f3n del territorio conforme lo dispuesto por la Asamblea General en la resoluci\u00f3n 2065<\/strong>, que inst\u00f3 a las dos partes a mantener negociaciones para encontrar una soluci\u00f3n pac\u00edfica y definitiva de la controversia\u201d.<\/p>\n\n\n\n<p>Asimismo, la representante indic\u00f3 que el Gobierno argentino hab\u00eda reiterado al secretario General de las Naciones Unidas -el portugu\u00e9s Ant\u00f3nio Guterres- su inter\u00e9s en los esfuerzos que pueda desarrollar para asistir a las partes en la disputa con el prop\u00f3sito de reanudar las negociaciones a trav\u00e9s de la misi\u00f3n de buenos oficios.<\/p>\n\n\n\n<p>Tambi\u00e9n advirti\u00f3 que \u201cel Reino Unido contin\u00faa desarrollando actividades unilaterales contrarias a la resoluci\u00f3n 31\/49 de la Asamblea General, que incluyen la exploraci\u00f3n y explotaci\u00f3n ilegal de recursos renovables y no renovables en el \u00e1rea en disputa\u201d.<\/p>\n\n\n\n<p>\u201cEl Reino Unido contin\u00faa desarrollando actividades unilaterales contrarias a la resoluci\u00f3n de la Asamblea General, que incluyen la exploraci\u00f3n y explotaci\u00f3n ilegal de recursos renovables y no renovables en el \u00e1rea en disputa\u201dEMBAJADORA SQUEFF<\/p>\n\n\n\n<p>En esa l\u00ednea, se\u00f1al\u00f3 que existe&nbsp;<strong>\u201cuna presencia militar desproporcionada en el Atl\u00e1ntico Sur, las cuales han sido denunciadas reiteradamente por la Argentina\u201d<\/strong>.<\/p>\n\n\n\n<p>En la primera jornada del debate, en el que participan los 193 Estados Miembros de la Organizaci\u00f3n, la Argentina recibi\u00f3 el respaldo de los pa\u00edses del Mercosur y Estados Asociados, la Comunidad de Estados Latinoamericanos y Caribe\u00f1os (Celac) y el Sistema de la Integraci\u00f3n Centroamericano (SICA), as\u00ed como de M\u00e9xico y Ecuador, en capacidad nacional.<\/p>\n\n\n\n<p>Ante este apoyo internacional,&nbsp;<strong>el secretario de Malvinas, Ant\u00e1rtida y Atl\u00e1ntico Sur, Guillermo Carmona<\/strong>, destac\u00f3 el aval recibido por Argentina en el tratamiento de la Cuesti\u00f3n Malvinas en la Cuarta Comisi\u00f3n y agradeci\u00f3 el trabajo de la delegaci\u00f3n argentina destacada en Nueva York, a cargo de la embajadora Squeff.<\/p>\n\n\n\n<p>La intervenci\u00f3n de los pa\u00edses<br><strong>M\u00e9xico<\/strong>, interviniendo en nombre de la Celac, record\u00f3 el inter\u00e9s permanente de los pa\u00edses de la regi\u00f3n en que los Gobiernos de la Argentina y del Reino Unido \u201creanuden las negociaciones a fin de encontrar, a la mayor brevedad posible, una soluci\u00f3n pac\u00edfica y definitiva a dicha disputa\u201d, de conformidad con la resoluci\u00f3n 2065 (XX) de la Asamblea General de las Naciones Unidas y otras resoluciones pertinentes de la ONU y de la Organizaci\u00f3n de los Estados Americanos (OEA).<\/p>\n\n\n\n<p>Inform\u00f3 asimismo que los Jefes de Estado y Gobierno de la Comunidad hab\u00edan solicitado a la Presidencia Pro Tempore que solicite al Secretario General de las Naciones Unidas que \u201crenueve los esfuerzos en el cumplimiento de la misi\u00f3n de buenos oficios sobre el tema\u201d.<\/p>\n\n\n\n<p><strong>En tanto, Brasil<\/strong>, en nombre del Mercosur y sus Estados Asociados, se\u00f1al\u00f3 que \u201clas Islas Malvinas son territorio argentino y que deb\u00eda observarse el principio de integridad territorial de los Estados, en conformidad con los principios esenciales de derecho internacional\u201d.<\/p>\n\n\n\n<p><img decoding=\"async\" src=\"https:\/\/www.telam.com.ar\/advf\/imagenes\/2020\/08\/5f2d28dc3e18d_1004x565.jpg\" alt=\"La diplom\u00e1tica reiter\u00f3 la disposici\u00f3n de Argentina \u201ca contribuir a la descolonizaci\u00f3n del territorio&quot;.\">La diplom\u00e1tica reiter\u00f3 la disposici\u00f3n de Argentina \u201ca contribuir a la descolonizaci\u00f3n del territorio\".<\/p>\n\n\n\n<p>A\u00f1adi\u00f3 que \u201cdesde la resoluci\u00f3n 2065 del a\u00f1o 1965, hasta el presente, la Asamblea General y el Comit\u00e9 Especial de Descolonizaci\u00f3n han reconocido que la cuesti\u00f3n de las Islas Malvinas es una disputa de soberan\u00eda que involucra a la Rep\u00fablica Argentina y el Reino Unido de Gran Breta\u00f1a e Irlanda del Norte, y que la manera de poner fin a la especial y particular situaci\u00f3n colonial de este caso es la soluci\u00f3n pac\u00edfica y negociada de la controversia entre las dos partes.\u201d<\/p>\n\n\n\n<p><strong>Guatemala<\/strong>, en nombre de los pa\u00edses del Sistema de Integraci\u00f3n Centroamericano (SICA), reiter\u00f3 el \u201cm\u00e1s firme respaldo de los pa\u00edses del grupo a los leg\u00edtimos derechos de Argentina en la disputa de soberan\u00eda sobre las Islas Malvinas, Georgias del Sur y Sandwich del Sur y los espacios mar\u00edtimos circundantes\u201d.<\/p>\n\n\n\n<p>El debate general de la Cuarta Comisi\u00f3n continuar\u00e1 durante los pr\u00f3ximos d\u00edas, y se esperan m\u00e1s intervenciones en respaldo a los derechos soberanos del pa\u00eds sobre los espacios en disputa y en apoyo a la reanudaci\u00f3n de las negociaciones entre la Argentina y el Reino Unido.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fue a trav\u00e9s de la embajadora Mar\u00eda del Carmen Squeff, quien apoy\u00f3 la postura nacional y\u00a0reiter\u00f3 la disposici\u00f3n de Argentina \u201ca contribuir a la descolonizaci\u00f3n del territorio\", al mismo tiempo, se\u00f1al\u00f3 que existe\u00a0\u201cuna presencia militar desproporcionada en el Atl\u00e1ntico Sur\", ya denunciadas por el pa\u00eds. La&nbsp;representante permanente de la Argentina ante las Naciones Unidas, la [&hellip;]<\/p>\n","protected":false},"author":40,"featured_media":315223,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_stopmodifiedupdate":false,"_modified_date":"","inline_featured_image":false},"categories":[5],"tags":[],"jetpack_featured_media_url":"https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2021\/10\/5a4e00048f4d4_1004x565.jpg","_links":{"self":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts\/315222"}],"collection":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/users\/40"}],"replies":[{"embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/comments?post=315222"}],"version-history":[{"count":1,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts\/315222\/revisions"}],"predecessor-version":[{"id":315224,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts\/315222\/revisions\/315224"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/media\/315223"}],"wp:attachment":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/media?parent=315222"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/categories?post=315222"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/tags?post=315222"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}