{"id":315197,"date":"2021-10-22T09:07:50","date_gmt":"2021-10-22T12:07:50","guid":{"rendered":"https:\/\/notinor.com\/jujuy\/?p=315197"},"modified":"2021-10-22T09:07:54","modified_gmt":"2021-10-22T12:07:54","slug":"un-viernes-caluroso-con-maxima-de-30o","status":"publish","type":"post","link":"https:\/\/notinor.com\/jujuy\/un-viernes-caluroso-con-maxima-de-30o\/","title":{"rendered":"Un viernes caluroso con m\u00e1xima de 30\u00ba"},"content":{"rendered":"\n<p>La m\u00ednima prevista para este viernes fue de 15\u00b0C con el cielo totalmente despejado. En cuanto a la m\u00e1xima el Servicio Meteorol\u00f3gico Nacional anuncia que va a llegar a los 31\u00b0C. Los vientos predominar\u00e1n desde el sector noroeste.El Servicio Meteorol\u00f3gico Nacional descarta lluvias durante la jornada.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/viapais.com.ar\/resizer\/_pBprGk1g_EzxLWdMWKOpy_uXO0=\/982x551\/smart\/cloudfront-us-east-1.images.arcpublishing.com\/grupoclarin\/HFSDEYTDHE2GCMDDHE3WIYTFGU.jpg\" alt=\"Se espera un fin de semana c\u00e1lido y soleado | V\u00eda Jujuy\" width=\"1176\" height=\"659\"\/><\/figure><\/div>\n\n\n\n<p>Para este viernes se prev\u00e9n marcas m\u00ednimas cercanas a 14\u00b0 y m\u00e1ximas de 31\u00b0, con cielo mayormente nublado.De acuerdo al parte Servicio Meteorol\u00f3gico Nacional, el clima se presentar\u00eda sin lluvias , y los vientos del noreste correr\u00e1n a una velocidad de entre 13 y 22 kil\u00f3metros por hora. La humedad ser\u00eda del 41 por ciento.<\/p>\n\n\n\n<p>El parte del servicio meteorol\u00f3gico prev\u00e9 que para despu\u00e9s del mediod\u00eda el cielo estar\u00e1 algo nublado y los vientos del sector este tendr\u00e1n velocidades estimadas entre 7 y 12km\/h. La temperatura pronosticada ser\u00eda de&nbsp;<strong>31 grados.<\/strong><\/p>\n\n\n\n<p>A la noche, el clima rondar\u00e1 los 24 grados, mientras que los vientos ser\u00e1n del noreste a una velocidad de 13 y 22 kil\u00f3metros por hora. No se esperan lluvias para esta franja del d\u00eda.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2021\/10\/rgrgrrggrg.jpg\" alt=\"\" class=\"wp-image-315199\" width=\"1168\" height=\"644\" srcset=\"https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2021\/10\/rgrgrrggrg.jpg 754w, https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2021\/10\/rgrgrrggrg-660x365.jpg 660w, https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2021\/10\/rgrgrrggrg-750x414.jpg 750w\" sizes=\"(max-width: 1168px) 100vw, 1168px\" \/><\/figure><\/div>\n\n\n\n<p>Como anticipo para s\u00e1bado y domingo, las condiciones ser\u00e1n similares, con cielo algo nublado y viento predominante del sector este.El tiempo en Jujuy estar\u00e1 s\u00faper agradable con cielo despejado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La m\u00ednima prevista para este viernes fue de 15\u00b0C con el cielo totalmente despejado. En cuanto a la m\u00e1xima el Servicio Meteorol\u00f3gico Nacional anuncia que va a llegar a los 31\u00b0C. Los vientos predominar\u00e1n desde el sector noroeste.El Servicio Meteorol\u00f3gico Nacional descarta lluvias durante la jornada. Para este viernes se prev\u00e9n marcas m\u00ednimas cercanas a [&hellip;]<\/p>\n","protected":false},"author":40,"featured_media":315200,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_stopmodifiedupdate":false,"_modified_date":"","inline_featured_image":false},"categories":[514],"tags":[],"jetpack_featured_media_url":"https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2021\/10\/HFSDEYTDHE2GCMDDHE3WIYTFGU-1.jpg","_links":{"self":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts\/315197"}],"collection":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/users\/40"}],"replies":[{"embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/comments?post=315197"}],"version-history":[{"count":1,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts\/315197\/revisions"}],"predecessor-version":[{"id":315201,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts\/315197\/revisions\/315201"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/media\/315200"}],"wp:attachment":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/media?parent=315197"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/categories?post=315197"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/tags?post=315197"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}