{"id":302457,"date":"2021-06-22T09:18:23","date_gmt":"2021-06-22T12:18:23","guid":{"rendered":"https:\/\/notinor.com\/jujuy\/?p=302457"},"modified":"2021-06-22T09:18:27","modified_gmt":"2021-06-22T12:18:27","slug":"labraron-mas-de-500-actas-por-el-mal-o-uso-o-la-no-utilizacion-del-barbijo","status":"publish","type":"post","link":"https:\/\/notinor.com\/jujuy\/labraron-mas-de-500-actas-por-el-mal-o-uso-o-la-no-utilizacion-del-barbijo\/","title":{"rendered":"Labraron m\u00e1s de 500 actas por el mal o uso o la no utilizaci\u00f3n del barbijo"},"content":{"rendered":"\n<p>As\u00ed lo inform\u00f3 la Polic\u00eda de Jujuy. Son resultados de los operativos del fin de semana largo en las ocho unidades regionales de la provincia.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" loading=\"lazy\" width=\"755\" height=\"480\" src=\"https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2020\/08\/Caminatas-755x480.jpg\" alt=\"\" class=\"wp-image-257383\" srcset=\"https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2020\/08\/Caminatas-755x480.jpg 755w, https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2020\/08\/Caminatas-574x365.jpg 574w, https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2020\/08\/Caminatas-768x488.jpg 768w, https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2020\/08\/Caminatas-750x477.jpg 750w, https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2020\/08\/Caminatas-1140x725.jpg 1140w, https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2020\/08\/Caminatas.jpg 1500w\" sizes=\"(max-width: 755px) 100vw, 755px\" \/><\/figure>\n\n\n\n<p>La Polic\u00eda de la Provincia intensific\u00f3 las tareas de control durante este fin de semana largo atendiendo a los festejos por el D\u00eda del Padre y as\u00ed evitar la propagaci\u00f3n del coronavirus.<\/p>\n\n\n\n<p>Bajo ese marco, la fuerza de seguridad desactiv\u00f3 una fiesta clandestina en Libertador General San Mart\u00edn y labr\u00f3 504 actas de infracci\u00f3n por el mal uso o la no utilizaci\u00f3n del barbijo o cubrebocas en la v\u00eda p\u00fablica.<\/p>\n\n\n\n<p>Desde la disposici\u00f3n del COE provincial en resguardar la salud p\u00fablica, la Polic\u00eda agudiz\u00f3 controles por el mantenimiento del distanciamiento social y el uso del barbijo, adem\u00e1s de controlar la restricci\u00f3n nocturna y velar por el estricto cumplimiento de todas las medidas de bioseguridad.<\/p>\n\n\n\n<p>Con respecto a los operativos de control sanitario, <strong>efectivos de las ocho unidades regionales labraron un total de<\/strong>\u00a0<strong>504 infracciones por falta de barbijo o mal uso del mismo en la v\u00eda p\u00fablica<\/strong>, desde que se fortalecieron los dispositivos de prevenci\u00f3n.<\/p>\n\n\n\n<p>El operativo de control implica recorridos y patrullajes estrat\u00e9gicos en barrios, plazas, lugares de esparcimiento, centro comercial y control vehicular entre otras tareas preventivas.<\/p>\n\n\n\n<p>En cuanto a las actividades permitidas (eventos deportivos y culturales), efectivos corroboraron que se concreten en las condiciones o medidas sanitarias dispuestas.<\/p>\n\n\n\n<p><strong>Fiestas clandestinas<\/strong><\/p>\n\n\n\n<p>En la madrugada del d\u00eda s\u00e1bado, en la ciudad de Libertador Gral. San Martin personal policial de la Unidad Regional N\u00ba 4 desarticularon una fiesta clandestina con menores de edad.<\/p>\n\n\n\n<p>El evento tuvo lugar en una vivienda particular del Barrio Pomelar de la ciudad ramale\u00f1a, donde 58 personas participaban de una fiesta que exced\u00eda el n\u00famero m\u00e1ximo establecido para el caso de reuniones sociales y no se cumpl\u00edan los protocolos sanitarios.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/media.prensa.jujuy.gob.ar\/p\/a5b71763ea186dc21bd10f785d5fad63\/adjuntos\/301\/imagenes\/000\/272\/0000272963\/seguridad.jpeg?0000-00-00-00-00-00\" alt=\"\"\/><\/figure>\n\n\n\n<p>Tras desalojar a los asistentes e identificar a los presentes, se corrobor\u00f3 que cinco eran menores de edad. Luego de identificar al propietario, el Juzgado Contravencional N\u00ba 2 dispuso labrar el acta de contravenci\u00f3n correspondiente.<\/p>\n\n\n\n<p>En tal sentido, es importante recalcar que se viene haciendo hincapi\u00e9 tambi\u00e9n en cuanto al\u00a0control\u00a0de reuniones sociales y familiares de personas, que no deber\u00e1 superar la cantidad de 10 integrantes.<\/p>\n\n\n\n<p><strong>Ante la presencia de un evento que no cumpla con el Decreto Acuerdo N\u00ba 2075 la Polic\u00eda solicita realizar la denuncia al 911 y al 0800-888-3368.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>As\u00ed lo inform\u00f3 la Polic\u00eda de Jujuy. Son resultados de los operativos del fin de semana largo en las ocho unidades regionales de la provincia. La Polic\u00eda de la Provincia intensific\u00f3 las tareas de control durante este fin de semana largo atendiendo a los festejos por el D\u00eda del Padre y as\u00ed evitar la propagaci\u00f3n [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":257383,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_stopmodifiedupdate":false,"_modified_date":"","inline_featured_image":false,"spay_email":"","jetpack_publicize_message":""},"categories":[2],"tags":[],"jetpack_featured_media_url":"https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2020\/08\/Caminatas.jpg","jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts\/302457"}],"collection":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/comments?post=302457"}],"version-history":[{"count":1,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts\/302457\/revisions"}],"predecessor-version":[{"id":302467,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts\/302457\/revisions\/302467"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/media\/257383"}],"wp:attachment":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/media?parent=302457"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/categories?post=302457"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/tags?post=302457"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}