{"id":298163,"date":"2021-05-17T09:34:56","date_gmt":"2021-05-17T12:34:56","guid":{"rendered":"https:\/\/notinor.com\/jujuy\/?p=298163"},"modified":"2021-05-17T09:35:01","modified_gmt":"2021-05-17T12:35:01","slug":"arrestaron-a-65-personas-que-participaban-de-una-fiesta-electronica-en-ocloyas","status":"publish","type":"post","link":"https:\/\/notinor.com\/jujuy\/arrestaron-a-65-personas-que-participaban-de-una-fiesta-electronica-en-ocloyas\/","title":{"rendered":"Arrestaron a 65 personas que participaban de una fiesta electr\u00f3nica en Ocloyas"},"content":{"rendered":"\n<p><strong>Una fiesta electr\u00f3nica clandestina fue desbaratada esta madrugada en la localidad de Ocloyas y 65 de los participantes terminaron arrestados<\/strong>.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/somosjujuy-wordpress.s3.amazonaws.com\/wp-content\/uploads\/2021\/05\/16182818\/foto-fiesta.jpg\" alt=\"\"\/><\/figure><\/div>\n\n\n\n<p>Luego de un minucioso trabajo de inteligencia llevado a cabo por detectives policiales, se pudo saber que se estar\u00eda llevando a cabo una fiesta clandestina en una finca de esa localidad, por lo que posteriormente se logr\u00f3 constatar que el evento se desarrollaba en una casa de campo ubicada en Ruta Provincial 5, altura del Paraje Membrillo.<\/p>\n\n\n\n<p>Despu\u00e9s de recabar las pruebas necesarias, y tras ser puestas a consideraci\u00f3n de las autoridades contravencionales, se orden\u00f3 que diferentes unidades operativas se dirijan al lugar a fin de hacer cesar el evento.<\/p>\n\n\n\n<p>De inmediato<strong>\u00a0Personal de Infanter\u00eda, Comando de Seguridad, Seguridad Vial y otras \u00e1reas intervinieron para poner fin a una fiesta electr\u00f3nica que no cumpl\u00eda ninguna medida sanitaria<\/strong>.<\/p>\n\n\n\n<p><strong>Cerca de 65 personas entre hombres y mujeres participaron del evento<\/strong>, que no cumpl\u00eda ninguna medida sanitaria y violaba las normativas vigentes por la pandemia.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/media.todojujuy.com\/p\/8c21e03e26c4d2917c9dc65cf77abb7f\/adjuntos\/227\/imagenes\/003\/076\/0003076145\/clandestina-ocloyas-jujuyjpg.jpg?0000-00-00-00-00-00\" alt=\"Una fiesta electr\u00f3nica en Ocloyas termin\u00f3 con 65 arrestados\" width=\"873\" height=\"491\"\/><\/figure><\/div>\n\n\n\n<p><strong>Las personas fueron demoradas<\/strong>\u00a0y trasladadas a las dependencias de la Central de Polic\u00eda en San Salvador, mientras que\u00a0<strong>se secuestraron m\u00e1s de 20 veh\u00edculos.<\/strong><\/p>\n\n\n\n<p>La justicia contravencional dispuso que a cada uno de los participantes se les labre\u00a0<strong>la multa correspondiente.<\/strong><\/p>\n\n\n\n<p>El evento fue organizado por una productora de la provincia de Salta, y la entrada para poder acceder a la fiesta ten\u00eda un costo de entre 4 mil y 7 mil pesos.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una fiesta electr\u00f3nica clandestina fue desbaratada esta madrugada en la localidad de Ocloyas y 65 de los participantes terminaron arrestados. Luego de un minucioso trabajo de inteligencia llevado a cabo por detectives policiales, se pudo saber que se estar\u00eda llevando a cabo una fiesta clandestina en una finca de esa localidad, por lo que posteriormente [&hellip;]<\/p>\n","protected":false},"author":40,"featured_media":298167,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_stopmodifiedupdate":false,"_modified_date":"","inline_featured_image":false},"categories":[3],"tags":[],"jetpack_featured_media_url":"https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2021\/05\/una-fiesta-electronica-ocloyas-termino-65-arrestados.jpg","_links":{"self":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts\/298163"}],"collection":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/users\/40"}],"replies":[{"embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/comments?post=298163"}],"version-history":[{"count":1,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts\/298163\/revisions"}],"predecessor-version":[{"id":298168,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts\/298163\/revisions\/298168"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/media\/298167"}],"wp:attachment":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/media?parent=298163"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/categories?post=298163"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/tags?post=298163"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}