{"id":279181,"date":"2020-12-09T15:39:50","date_gmt":"2020-12-09T18:39:50","guid":{"rendered":"https:\/\/notinor.com\/jujuy\/?p=279181"},"modified":"2020-12-09T15:39:53","modified_gmt":"2020-12-09T18:39:53","slug":"desarrollan-un-yogur-contra-el-coronavirus","status":"publish","type":"post","link":"https:\/\/notinor.com\/jujuy\/desarrollan-un-yogur-contra-el-coronavirus\/","title":{"rendered":"Desarrollan un \"yogur\" contra el coronavirus"},"content":{"rendered":"\n<p>El Instituto de Medicina Molecular de San Petesburgo, en Rusia, cre\u00f3 una droga de administraci\u00f3n oral que genera anticuerpos del Covid-19, seg\u00fan las pruebas de laboratorios con animales.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" loading=\"lazy\" width=\"750\" height=\"368\" src=\"https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2020\/12\/yogur.jpg\" alt=\"\" class=\"wp-image-279187\" srcset=\"https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2020\/12\/yogur.jpg 750w, https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2020\/12\/yogur-660x324.jpg 660w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><\/figure>\n\n\n\n<p>\"La respuesta inmune sobre las mucosas de animales de laboratorio es muy buena, los anticuerpos espec\u00edficos se forman sobre las mucosas y en la sangre\", expres\u00f3 Alex\u00e1nder Sov\u00f3rov, director del departamento de microbiolog\u00eda molecular de la instituci\u00f3n.<\/p>\n\n\n\n<p>Las especies utilizadas para el experimento no fueron especificadas por el experto.<\/p>\n\n\n\n<p>Por su parte, autoridades sanitarias de Estados Unidos afirmaron que la vacuna del laboratorio Pfizer garantiza la protecci\u00f3n contra el Covid-19 desde la primera dosis.<\/p>\n\n\n\n<p>Acerca del nuevo f\u00e1rmaco, el vicepresidente de la Academia de Ciencias de Rusia, Vlad\u00edmir Chejonin, se\u00f1al\u00f3 que \"gracias a que la administraci\u00f3n de la vacuna se recibe por v\u00eda oral, la m\u00e1xima respuesta inmune se produce sobre las mucosas, y por eso (la vacuna) se denomina mucosal\".<\/p>\n\n\n\n<p>Tambi\u00e9n explic\u00f3 que el pr\u00f3ximo paso de los cient\u00edficos es comprobar la efectividad de la vacuna en una situaci\u00f3n de contagio real.<\/p>\n\n\n\n<p>El desaf\u00edo que presenta esta cuesti\u00f3n es que San Petesburg. o posee las instalaciones adecuadas para realizar semejantes pruebas con animales, por lo que los investigadores est\u00e1n a la espera de su turno para hacerlo en otra ubicaci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Instituto de Medicina Molecular de San Petesburgo, en Rusia, cre\u00f3 una droga de administraci\u00f3n oral que genera anticuerpos del Covid-19, seg\u00fan las pruebas de laboratorios con animales. \"La respuesta inmune sobre las mucosas de animales de laboratorio es muy buena, los anticuerpos espec\u00edficos se forman sobre las mucosas y en la sangre\", expres\u00f3 Alex\u00e1nder [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":279187,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_stopmodifiedupdate":false,"_modified_date":"","inline_featured_image":false,"spay_email":"","jetpack_publicize_message":""},"categories":[6],"tags":[],"jetpack_featured_media_url":"https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2020\/12\/yogur.jpg","jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts\/279181"}],"collection":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/comments?post=279181"}],"version-history":[{"count":1,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts\/279181\/revisions"}],"predecessor-version":[{"id":279188,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts\/279181\/revisions\/279188"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/media\/279187"}],"wp:attachment":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/media?parent=279181"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/categories?post=279181"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/tags?post=279181"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}