{"id":279162,"date":"2020-12-09T11:18:18","date_gmt":"2020-12-09T14:18:18","guid":{"rendered":"https:\/\/notinor.com\/jujuy\/?p=279162"},"modified":"2020-12-09T11:18:23","modified_gmt":"2020-12-09T14:18:23","slug":"marte-cientificos-descubren-un-lugar-donde-pudo-haber-vida","status":"publish","type":"post","link":"https:\/\/notinor.com\/jujuy\/marte-cientificos-descubren-un-lugar-donde-pudo-haber-vida\/","title":{"rendered":"Marte: cient\u00edficos descubren un lugar donde pudo haber vida"},"content":{"rendered":"\n<p>Al ser el planeta m\u00e1s cercano a la Tierra, Marte siempre ha despertado la fascinaci\u00f3n de los cient\u00edficos que desplegaron varias investigaciones en la b\u00fasqueda de alg\u00fan tipo de vida surgida en el pasado remoto. En este sentido,\u00a0<strong>un reciente descubrimiento demostr\u00f3 que en la superficie de Marte hubo agua l\u00edquida<\/strong>\u00a0en la que se pudo gestar la vida tal cual la conocemos.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/images.pagina12.com.ar\/styles\/focal_3_2_960x640\/public\/2020-12\/126341-whatsapp-20image-202020-12-08-20at-2019-38-38.jpeg?itok=Ocw2HSw2\" alt=\"\"\/><\/figure>\n\n\n\n<p>\u201cMucha evidencia morfol\u00f3gica y composicional en Marte sugiere abundante agua superficial sostenida por hidrolog\u00eda subterr\u00e1nea\u201d hace 3.700 o 4.100 millones de a\u00f1os (llamado \u2018E\u00f3n de No\u00e9'), expuso Lujendra Ojha, cient\u00edfico planetario nepal\u00e9s-estadounidense integrante del equipo de investigaci\u00f3n.<\/p>\n\n\n\n<p>De acuerdo a&nbsp;la novedosa investigaci\u00f3n, realizada por astr\u00f3nomos de la Universidad Rutgers, el Dartmouth College, la Universidad Estatal de Louisiana y el Planetary Science Institute, \"<strong>el \u2018Planeta rojo\u2019 recibe el 43% de la luminosidad del Sol si lo comparamos a la realidad terrestre, por lo tanto, el clima debi\u00f3 ser, en sus etapas primigenias, extremadamente fr\u00edo con presencia de agua l\u00edquida<\/strong>.&nbsp;<\/p>\n\n\n\n<p>El grupo completo de astr\u00f3nomos calcul\u00f3 el flujo de calor exacto para producir agua de deshielo y lagos subglaciares en el planeta fr\u00edo y helado. Determinaron que las condiciones del derretimiento de agua subterr\u00e1nea se habr\u00edan dado, sumadas a la actividad volc\u00e1nica y a los meteoritos estrellados.<\/p>\n\n\n\n<p>\"<strong>El calor geot\u00e9rmico de Marte pudo haberse expandido desde sus profundidades, lo que conlleva a apuntar que el mejor lugar donde pudo haber existido vida fue el subsuelo<\/strong>\", expone el documento publicado en la plataforma de la revista Science Advances.<\/p>\n\n\n\n<p>\u201c<strong>El subsuelo puede representar el entorno habitable m\u00e1s longevo de Marte<\/strong>\u201d, recalc\u00f3 Ojha. Adem\u00e1s, los cient\u00edficos postularon la presencia de agua salada porque dicha salinidad reduce el punto de congelaci\u00f3n del H2O.<\/p>\n\n\n\n<p>Por otro lado, el vulcanismo de lodo en el cuarto planeta del sistema solar habr\u00eda empujado a los sedimentos h\u00famedos hacia arriba; entonces, el agua se sublimar\u00eda \u2014pasar\u00eda de estado s\u00f3lido a gaseoso\u2014 a la superficie. Sin embargo, todav\u00eda no hay una respuesta clara e irrefutable.<\/p>\n\n\n\n<h5><\/h5>\n\n\n\n<h5><a href=\"https:\/\/www.pagina12.com.ar\/310721-asombroso-descubrimiento-las-sondas-voyager-detectaron-por-p\"><\/a><\/h5>\n","protected":false},"excerpt":{"rendered":"<p>Al ser el planeta m\u00e1s cercano a la Tierra, Marte siempre ha despertado la fascinaci\u00f3n de los cient\u00edficos que desplegaron varias investigaciones en la b\u00fasqueda de alg\u00fan tipo de vida surgida en el pasado remoto. En este sentido,\u00a0un reciente descubrimiento demostr\u00f3 que en la superficie de Marte hubo agua l\u00edquida\u00a0en la que se pudo gestar [&hellip;]<\/p>\n","protected":false},"author":40,"featured_media":279163,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_stopmodifiedupdate":false,"_modified_date":"","inline_featured_image":false,"spay_email":"","jetpack_publicize_message":""},"categories":[17,13],"tags":[],"jetpack_featured_media_url":"https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2020\/12\/xcxcvbgf.png","jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts\/279162"}],"collection":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/users\/40"}],"replies":[{"embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/comments?post=279162"}],"version-history":[{"count":1,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts\/279162\/revisions"}],"predecessor-version":[{"id":279164,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts\/279162\/revisions\/279164"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/media\/279163"}],"wp:attachment":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/media?parent=279162"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/categories?post=279162"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/tags?post=279162"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}