{"id":255417,"date":"2020-07-27T11:47:56","date_gmt":"2020-07-27T14:47:56","guid":{"rendered":"https:\/\/notinor.com\/jujuy\/?p=255417"},"modified":"2020-08-24T12:19:49","modified_gmt":"2020-08-24T15:19:49","slug":"que-famosos-saldran-a-la-pista-en-la-primera-gala-del-cantando-2020","status":"publish","type":"post","link":"https:\/\/notinor.com\/jujuy\/que-famosos-saldran-a-la-pista-en-la-primera-gala-del-cantando-2020\/","title":{"rendered":"Qu\u00e9 famosos saldr\u00e1n a la pista en la primera gala del \u201cCantando 2020\u201d"},"content":{"rendered":"\n<p>Este lunes a las 22.30 horas comienza la gran apuesta de LaFlia con la conducci\u00f3n de \u00c1ngel de Brito y Laurita Fern\u00e1ndez en la pantalla de El Trece<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" loading=\"lazy\" width=\"750\" height=\"422\" src=\"https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2020\/07\/CANTANDO-1.jpg\" alt=\"\" class=\"wp-image-255419\" srcset=\"https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2020\/07\/CANTANDO-1.jpg 750w, https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2020\/07\/CANTANDO-1-649x365.jpg 649w, https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2020\/07\/CANTANDO-1-500x280.jpg 500w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><\/figure>\n\n\n\n<p>La espera termin\u00f3. Este lunes finalmente desde las 22.30 horas en la pantalla de El Trece vuelve el Cantando 2020 totalmente renovado. Angel de Brito y Laurita Fern\u00e1ndez ser\u00e1n los encargados de llevar adelante el reality de canto que pone primera y que en esta quinta edici\u00f3n tendr\u00e1 a veinte parejas de famosos y so\u00f1adores compitiendo por el t\u00edtulo.<\/p>\n\n\n\n<p>Habr\u00e1 un jurado de lujo, integrado por figuras del teatro, la televisi\u00f3n y la m\u00fasica, que evaluar\u00e1 las aptitudes vocales y esc\u00e9nicas de los participantes. Ellos son Moria Cas\u00e1n, Nacha Guevara, Pepito Cibri\u00e1n y Karina La Princesita.<\/p>\n\n\n\n<p>Seg\u00fan pudo saber Teleshow, la encargada en abrir la pista ser\u00e1 Carmen Barbieri y lo har\u00e1 al ritmo de Te quiero tanto, uno de los grandes \u00e9xitos de Sergio Denis. Sin lugar a dudas ser\u00e1 una gala muy especial para la actriz, debido a que hace algunos d\u00edas su hijo Federico le cont\u00f3 que se recuper\u00f3 del c\u00e1ncer de intestino -enfermedad que tambi\u00e9n padecieron su padre y abuelo- y se prev\u00e9 que ella cuente c\u00f3mo vivi\u00f3 todo ese proceso.<\/p>\n\n\n\n<p>La segunda famosa que har\u00e1 su presentaci\u00f3n ser\u00e1 Lola Latorre junto al influencer Lucas Spadafora. Ambos tendr\u00e1n la tarea de interpretar Te quiero m\u00e1s de Martina Tini Stoessel y Nacho. Luego, continuar\u00e1n Facundo Mazzei y Agustina Agazzani -la ex novia de Mart\u00edn Baclini- quienes entonar\u00e1n Torero de Chayanne y \u201csi hay tiempo\u201d informaron desde la producci\u00f3n cerrar\u00e1 este primer programa Jey Mammon y Carla del Huerto que cantar\u00e1n Rescata mi coraz\u00f3n de Manuel Wirzt.<\/p>\n\n\n\n<p>\u201cYo voy a mantener mi esencia period\u00edstica. Mi rol es distinto porque como jurado me encargaba de hacer las preguntas m\u00e1s inc\u00f3modas y, en este caso, voy a ser el anfitri\u00f3n. Pero le voy a preguntar a los participantes, a los jurados, a Laurita y a todos, aunque siempre desde el rol de conductor\u201d, reconoci\u00f3 \u00c1ngel de Brito a Teleshow horas antes de su debut como conductor en un ciclo de entretenimientos.<\/p>\n\n\n\n<p>El Cantando 2020 ser\u00e1 una de las pocas producciones en vivo que llegar\u00e1n este a\u00f1o a causa del coronavirus y como no podr\u00eda ser de otra manera, tendr\u00e1 su propia apertura a cargo de Karina La Princesita (Tambi\u00e9n jurado), Dami\u00e1n C\u00f3rdoba, Rochi Igarz\u00e1rbal, Germ\u00e1n \u201cTripa\u201d Tripel y Flor Otero. Todos ellos presentar\u00e1n un mash up de temas populares de m\u00fasica nacional para abrir el certamen.<\/p>\n\n\n\n<p>Adem\u00e1s, competir\u00e1n: Miguel \u00c1ngel Rodr\u00edguez con Lula Rosenthal; Dan Breitman con Florencia Anca; Laura Novoa con Patricio Arellano; Melina Lezcano con Juan P\u00e9rsico; Gladys La Bomba Tucumana y su hijo Tyago Griffo; Sofi Morandi y Bruno Coccia; Esmeralda Mitre y Nicol\u00e1s Serraiti; Flor Torrente y Michel Hersch; Lizardo Ponce y Luc\u00eda Villar; Adabel Guerrero y Leandro Bassano; Flopy Tesouro y Pablo Turturiello; Mariana Brey y Fran Eizaguirre; Brian Lanzellotta y \u00c1ngela Leiva; Karina Jelinek y Manuel Victoria; Federico Salles con Cande Molfese y Agust\u00edn Sierra e Inbal Comedi.<\/p>\n\n\n\n<p>Cabe destacar que LaFlia trabaj\u00f3 contrarreloj para la salida al aire del programa que estar\u00e1 adaptado a los tiempos de la pandemia. De esta manera, se respetar\u00e1 la distancia social y se cumplir\u00e1n con todas las medidas de prevenci\u00f3n para evitar posibles contagios entre los integrantes del ciclo. La productora eligi\u00f3 poner el foco en este formato y dejar para m\u00e1s adelante el estreno de ShowMatch, el cl\u00e1sico programa que comanda con mucho \u00e9xito Marcelo Tinelli. El regreso estaba previsto para abril, pero se fue postergando. Es probable que arranque en septiembre, pero todav\u00eda no hay nada definido.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este lunes a las 22.30 horas comienza la gran apuesta de LaFlia con la conducci\u00f3n de \u00c1ngel de Brito y Laurita Fern\u00e1ndez en la pantalla de El Trece La espera termin\u00f3. Este lunes finalmente desde las 22.30 horas en la pantalla de El Trece vuelve el Cantando 2020 totalmente renovado. Angel de Brito y Laurita [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":255419,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_stopmodifiedupdate":false,"_modified_date":"","inline_featured_image":false,"spay_email":"","jetpack_publicize_message":""},"categories":[21],"tags":[],"jetpack_featured_media_url":"https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2020\/07\/CANTANDO-1.jpg","jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts\/255417"}],"collection":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/comments?post=255417"}],"version-history":[{"count":1,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts\/255417\/revisions"}],"predecessor-version":[{"id":255420,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts\/255417\/revisions\/255420"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/media\/255419"}],"wp:attachment":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/media?parent=255417"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/categories?post=255417"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/tags?post=255417"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}