{"id":255407,"date":"2020-07-27T11:18:40","date_gmt":"2020-07-27T14:18:40","guid":{"rendered":"https:\/\/notinor.com\/jujuy\/?p=255407"},"modified":"2020-07-27T11:18:42","modified_gmt":"2020-07-27T14:18:42","slug":"america-latina-se-convirtio-en-el-foco-de-la-pandemia","status":"publish","type":"post","link":"https:\/\/notinor.com\/jujuy\/america-latina-se-convirtio-en-el-foco-de-la-pandemia\/","title":{"rendered":"Am\u00e9rica Latina se convirti\u00f3 en el foco de la pandemia"},"content":{"rendered":"\n<p>La situaci\u00f3n est\u00e1 cada vez peor en la regi\u00f3n: ya suman 4.327.160 casos de Covid-19 y representan el 26,83% de los infectados en el mundo.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" loading=\"lazy\" width=\"750\" height=\"359\" src=\"https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2020\/07\/LATINA.jpg\" alt=\"\" class=\"wp-image-255408\" srcset=\"https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2020\/07\/LATINA.jpg 750w, https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2020\/07\/LATINA-660x316.jpg 660w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><\/figure>\n\n\n\n<p>Los casos de coronavirus en Am\u00e9rica Latina superaron por primera vez al total de contagiados en el norte anglosaj\u00f3n, en medio de un recrudecimiento de la enfermedad en Brasil, M\u00e9xico, Colombia y Argentina en los \u00faltimos d\u00edas. De acuerdo con el conteo, realizado sobre la base de datos entregados por los gobiernos de cada pa\u00eds, Am\u00e9rica Latina sumaba este domingo 4.327.160 casos frente a los 4.308.495 contagios de Am\u00e9rica del Norte (Estados Unidos y Canad\u00e1).<\/p>\n\n\n\n<p>De esta forma, la regi\u00f3n pas\u00f3 a ser la m\u00e1s afectada en el mundo por el coronavirus. En las \u00faltimas 24 horas, Am\u00e9rica Latina tuvo 83.605 nuevos contagios frente a 66.124 en Estados Unidos y Canad\u00e1. El alza en esta parte del continente se debe principalmente a un mayor n\u00famero de contagios en Brasil, M\u00e9xico, Per\u00fa, Colombia y Argentina, y en menor grado, Chile.<\/p>\n\n\n\n<p>Adem\u00e1s, de acuerdo con el conteo, Latinoam\u00e9rica representa el 26,83% de los casos de coronavirus a nivel mundial, frente al 26,72% de los pa\u00edses de Am\u00e9rica del Norte. Estados Unidos sigue siendo el pa\u00eds con mayor n\u00famero de contagiados y fallecidos en el mundo -casi 4,2 millones y algo m\u00e1s de 143.000, respectivamente-, seguido por Brasil -casi 2,4 millones y cerca de 87.000-.<\/p>\n\n\n\n<p>M\u00e9xico, Per\u00fa y Chile tambi\u00e9n aparecen entre las 10 naciones con m\u00e1s casos. En los \u00faltimos d\u00edas, Colombia y Argentina vieron un fuerte aumento de los casos de coronavirus en sus territorios y actualmente se encuentran en los puestos 15 y 20 entre los pa\u00edses m\u00e1s afectados, respectivamente.<\/p>\n\n\n\n<p>La pandemia de Covid-19 sigue creciendo en todo el mundo. La Organizaci\u00f3n Mundial de la Salud (OMS) report\u00f3 el viernes un aumento r\u00e9cord de nuevos casos de coronavirus a nivel global, con un total de 284.196 infecciones en 24 horas. El 17 de julio, la India se convirti\u00f3 en el tercer pa\u00eds del mundo en registrar m\u00e1s de un mill\u00f3n de casos de la enfermedad, s\u00f3lo por detr\u00e1s de Estados Unidos y Brasil. Los epidemi\u00f3logos dicen que es probable que le falten meses para alcanzar el pico de contagios.<\/p>\n\n\n\n<p>Despu\u00e9s de que el primer caso de Covid-19 se report\u00f3 en Wuhan, China, a fines del a\u00f1o pasado, tom\u00f3 cerca de 15 semanas llegar a los 2 millones de casos. En tanto, s\u00f3lo tom\u00f3 ocho d\u00edas para superar las 15 millones de infecciones desde los 13 millones. En estos momentos, la cifra de contagiados a nivel mundial supera los 16,1 millones de personas.<\/p>\n\n\n\n<p>Los expertos en salud subrayan que los datos oficiales casi con toda seguridad no informan de todas las infecciones y muertes por coronavirus, en particular en los pa\u00edses con una capacidad de pruebas limitada.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La situaci\u00f3n est\u00e1 cada vez peor en la regi\u00f3n: ya suman 4.327.160 casos de Covid-19 y representan el 26,83% de los infectados en el mundo. Los casos de coronavirus en Am\u00e9rica Latina superaron por primera vez al total de contagiados en el norte anglosaj\u00f3n, en medio de un recrudecimiento de la enfermedad en Brasil, M\u00e9xico, [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":255408,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_stopmodifiedupdate":false,"_modified_date":"","inline_featured_image":false,"spay_email":"","jetpack_publicize_message":""},"categories":[6],"tags":[],"jetpack_featured_media_url":"https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2020\/07\/LATINA.jpg","jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts\/255407"}],"collection":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/comments?post=255407"}],"version-history":[{"count":1,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts\/255407\/revisions"}],"predecessor-version":[{"id":255409,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts\/255407\/revisions\/255409"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/media\/255408"}],"wp:attachment":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/media?parent=255407"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/categories?post=255407"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/tags?post=255407"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}