{"id":21799,"date":"2015-04-01T03:00:10","date_gmt":"2015-04-01T06:00:10","guid":{"rendered":"http:\/\/notinor.com\/jujuy\/?p=21799"},"modified":"2015-04-01T03:03:04","modified_gmt":"2015-04-01T06:03:04","slug":"trucos-juga-al-pac-man-dentro-de-google-maps-por-las-calles-de-tu-ciudad","status":"publish","type":"post","link":"https:\/\/notinor.com\/jujuy\/trucos-juga-al-pac-man-dentro-de-google-maps-por-las-calles-de-tu-ciudad\/","title":{"rendered":"Trucos: jug\u00e1 al Pac-Man dentro de Google Maps por las calles de tu ciudad"},"content":{"rendered":"<p><a href=\"http:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2015\/04\/pacman.gif\"><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter  wp-image-21800\" src=\"http:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2015\/04\/pacman.gif\" alt=\"pacman\" width=\"371\" height=\"209\" \/><\/a><\/p>\n<p>Dig\u00e1mosle adi\u00f3s a nuestra productividad laboral con este homenaje al personaje creado por Toru Iwatani.<br \/>\nCon motivo de la celebraci\u00f3n de April Fool's Day en los Estados Unidos, Google realiz\u00f3 una versi\u00f3n de Pac-Man que puede ser jugada dentro de Google Maps.<\/p>\n<p>Los fantasmas Blinky, Pinky, Inky y Clyde se enfrentar\u00e1n al redondeado personaje en las calles del nuestro planeta.<\/p>\n<p>El a\u00f1o pasado, Google puso a sus usuarios a capturar Pok\u00e9mon dentro de esta misma aplicaci\u00f3n y ahora se vuelve m\u00e1s retro al mostrar el juego creado originalmente por Toru Iwatani.<\/p>\n<p>Para poder jugar solamente tienes que escoger un mapa que tenga muchos caminos cruzados a manera de cuadr\u00edcula. En la parte inferior izquierda estar\u00e1 situado un bot\u00f3n que cambiar\u00e1 todo el mapa por la interfaz cl\u00e1sica del videojuego. Para controlar a Pac-Man desde tu browser tienes que utilizar las flechas direccionales mientras que desde tu m\u00f3vil tienes que deslizar el dedo en la direcci\u00f3n correcta para mover al comep\u00edldoras.<\/p>\n<p>Puedes utilizar en web los navegadores Safari, Internet Explorer y Chrome para jugar. Desde m\u00f3vil debes tener la versi\u00f3n m\u00e1s reciente de Maps (4.4 en iOS y 9.6 en Android).7<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dig\u00e1mosle adi\u00f3s a nuestra productividad laboral con este homenaje al personaje creado por Toru Iwatani. Con motivo de la celebraci\u00f3n de April Fool's Day en los Estados Unidos, Google realiz\u00f3 una versi\u00f3n de Pac-Man que puede ser jugada dentro de Google Maps. Los fantasmas Blinky, Pinky, Inky y Clyde se enfrentar\u00e1n al redondeado personaje en [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":21800,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_stopmodifiedupdate":false,"_modified_date":"","inline_featured_image":false},"categories":[16],"tags":[],"jetpack_featured_media_url":"https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2015\/04\/pacman.gif","_links":{"self":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts\/21799"}],"collection":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/comments?post=21799"}],"version-history":[{"count":3,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts\/21799\/revisions"}],"predecessor-version":[{"id":21803,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts\/21799\/revisions\/21803"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/media\/21800"}],"wp:attachment":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/media?parent=21799"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/categories?post=21799"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/tags?post=21799"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}