{"id":149572,"date":"2017-12-13T11:45:25","date_gmt":"2017-12-13T14:45:25","guid":{"rendered":"http:\/\/notinor.com\/jujuy\/?p=149572"},"modified":"2017-12-13T11:45:25","modified_gmt":"2017-12-13T14:45:25","slug":"el-lunes-18-se-reubicara-a-los-ingresantes-a-primer-ano-que-aun-no-cuentan-con-banco","status":"publish","type":"post","link":"https:\/\/notinor.com\/jujuy\/el-lunes-18-se-reubicara-a-los-ingresantes-a-primer-ano-que-aun-no-cuentan-con-banco\/","title":{"rendered":"El lunes 18 se reubicar\u00e1 a los ingresantes a primer a\u00f1o que aun no cuentan con banco"},"content":{"rendered":"<p>Desde el Ministerio de Educaci\u00f3n informaron que este lunes 18, los ingresantes a primer a\u00f1o que no obtuvieron banco debido a los resultados de los ex\u00e1menes, y los que no rindieron, tendr\u00e1n la posibilidad de ser inscriptos en aquellos establecimientos secundarios p\u00fablicos que aun cuentan con vacantes.<\/p>\n<p>Este lunes a las 8:30 en el Colegio N\u00b0 3 Exodo Juje\u00f1o, sito sobre calle Independencia entre Balccarce y Lamadrid, se proceder\u00e1 a la reubicaci\u00f3n de los alumnos que se quedaron sin vacante debido a los resultados, y tambi\u00e9n se ubicar\u00e1 a los que no rindieron examen.<\/p>\n<p>Las reubicaciones se realizar\u00e1n por \u00f3rden de m\u00e9rito, y se tendr\u00e1 en cuenta el domicilio que figura en el DNI. Por lo que se deber\u00e1 asistir munidos del DNI y de la tirilla de puntaje obtenido en los examenes.<\/p>\n<p>La educaci\u00f3n es un derecho constitucional y el Estado debe garantizar que cada estudiante tenga una vacante en un establecimiento p\u00fablico.<\/p>\n<p><a href=\"http:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2017\/12\/secundario-3.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-149578\" src=\"http:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2017\/12\/secundario-3.jpg\" alt=\"secundario 3\" width=\"927\" height=\"618\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Desde el Ministerio de Educaci\u00f3n informaron que este lunes 18, los ingresantes a primer a\u00f1o que no obtuvieron banco debido a los resultados de los ex\u00e1menes, y los que no rindieron, tendr\u00e1n la posibilidad de ser inscriptos en aquellos establecimientos secundarios p\u00fablicos que aun cuentan con vacantes. Este lunes a las 8:30 en el Colegio [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":149578,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_stopmodifiedupdate":false,"_modified_date":"","inline_featured_image":false},"categories":[2],"tags":[],"jetpack_featured_media_url":"https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2017\/12\/secundario-3.jpg","_links":{"self":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts\/149572"}],"collection":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/comments?post=149572"}],"version-history":[{"count":1,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts\/149572\/revisions"}],"predecessor-version":[{"id":149579,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts\/149572\/revisions\/149579"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/media\/149578"}],"wp:attachment":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/media?parent=149572"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/categories?post=149572"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/tags?post=149572"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}