{"id":139625,"date":"2017-10-11T16:39:30","date_gmt":"2017-10-11T19:39:30","guid":{"rendered":"http:\/\/notinor.com\/jujuy\/?p=139625"},"modified":"2017-10-11T21:02:30","modified_gmt":"2017-10-12T00:02:30","slug":"elsa-flores-me-obligaron-a-firmar-los-cheques","status":"publish","type":"post","link":"https:\/\/notinor.com\/jujuy\/elsa-flores-me-obligaron-a-firmar-los-cheques\/","title":{"rendered":"Elsa Flores, intendenta de Calilegua: \"Me obligaron a firmar los cheques\""},"content":{"rendered":"<p>Elsa Flores concurri\u00f3 al Juzgado de Control N\u00b0 4 acompa\u00f1ada de su abogado, en el marco de la ampliaci\u00f3n de imputaci\u00f3n que hizo la fiscal\u00eda, tanto la intendente de Calilegua como as\u00ed tambi\u00e9n Julio Mois\u00e9s y Ram\u00f3n Ale fueron imputados como \u201cpart\u00edcipes necesarios del delito de fraude a la administraci\u00f3n p\u00fablica por administraci\u00f3n infiel, cuatro hechos para cada uno en concurso real\u201d.<\/p>\n<p>Seg\u00fan declaraciones de Flores, esta fue obligada por la Tupac Amaru a firmar cheques. La intendenta adem\u00e1s expres\u00f3 que \"Soy la m\u00e1s interesada porque esto se aclare porque en Calilegua hay muchas casas que no se han construido. Las cooperativas de la Tupac recibieron los fondos y no se hicieron las casas\", afirm\u00f3 la jefa comunal a su salida del juzgado.<\/p>\n<p><a href=\"http:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2017\/10\/WhatsApp-Image-2017-10-11-at-16.37.29.jpeg\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-139627 size-large\" src=\"http:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2017\/10\/WhatsApp-Image-2017-10-11-at-16.37.29-800x600.jpeg\" alt=\"WhatsApp Image 2017-10-11 at 16.37.29\" width=\"800\" height=\"600\" srcset=\"https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2017\/10\/WhatsApp-Image-2017-10-11-at-16.37.29-800x600.jpeg 800w, https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2017\/10\/WhatsApp-Image-2017-10-11-at-16.37.29-300x225.jpeg 300w, https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2017\/10\/WhatsApp-Image-2017-10-11-at-16.37.29.jpeg 1280w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n<p>\"Me obligaron a firmar los cheques porque si no me hac\u00edan manifestaci\u00f3n en el municipio\" explic\u00f3 Elsa Flores, no obstante no quiso brindar nombres de los supuestos responsables de los delitos cometidos.<\/p>\n<p>Adem\u00e1s la funcionaria remarc\u00f3 que fueron en total 160 viviendas las que no se construyeron en Calilegua adem\u00e1s de manifestar que vivi\u00f3 situaciones de amenaza constante por parte de la organizaci\u00f3n social de Milagro Sala.<\/p>\n<p>Cabe recordar que la jefa comunal de Calilegua anteriormente declaro que\u00a0 a cada intento de ingresar a los barrios para controlar la actividad de las cooperativas s\u00f3lo recib\u00eda amenazas.<\/p>\n<p><a href=\"http:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2017\/10\/22429425_10155865025479708_1195246020_o.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-139626 size-large\" src=\"http:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2017\/10\/22429425_10155865025479708_1195246020_o-800x600.jpg\" alt=\"22429425_10155865025479708_1195246020_o\" width=\"800\" height=\"600\" srcset=\"https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2017\/10\/22429425_10155865025479708_1195246020_o-800x600.jpg 800w, https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2017\/10\/22429425_10155865025479708_1195246020_o-300x225.jpg 300w, https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2017\/10\/22429425_10155865025479708_1195246020_o.jpg 1280w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n<p>Dentro del cronograma de citaciones en el marco de esta causa, ma\u00f1ana est\u00e1 previsto que cumplan con el tr\u00e1mite de notificaci\u00f3n, los ex funcionarios de la Unidad Ejecutora Provincial H\u00e9ctor Carrizo y Jos\u00e9 Luis Mercado y el viernes ser\u00e1 el turno del ex ministro de Tierra y Vivienda de la anterior gesti\u00f3n, Luis Cosentini, y el\u00a0 ex presidente del Instituto de Viviendas y Urbanismo de Jujuy, Lucio Abreg\u00fa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Elsa Flores concurri\u00f3 al Juzgado de Control N\u00b0 4 acompa\u00f1ada de su abogado, en el marco de la ampliaci\u00f3n de imputaci\u00f3n que hizo la fiscal\u00eda, tanto la intendente de Calilegua como as\u00ed tambi\u00e9n Julio Mois\u00e9s y Ram\u00f3n Ale fueron imputados como \u201cpart\u00edcipes necesarios del delito de fraude a la administraci\u00f3n p\u00fablica por administraci\u00f3n infiel, cuatro [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":139627,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_stopmodifiedupdate":false,"_modified_date":"","inline_featured_image":false},"categories":[485],"tags":[],"jetpack_featured_media_url":"https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2017\/10\/WhatsApp-Image-2017-10-11-at-16.37.29.jpeg","_links":{"self":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts\/139625"}],"collection":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/comments?post=139625"}],"version-history":[{"count":2,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts\/139625\/revisions"}],"predecessor-version":[{"id":139709,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts\/139625\/revisions\/139709"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/media\/139627"}],"wp:attachment":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/media?parent=139625"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/categories?post=139625"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/tags?post=139625"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}