{"id":139564,"date":"2017-10-11T11:03:01","date_gmt":"2017-10-11T14:03:01","guid":{"rendered":"http:\/\/notinor.com\/jujuy\/?p=139564"},"modified":"2017-10-11T11:03:01","modified_gmt":"2017-10-11T14:03:01","slug":"de-que-manera-los-telefonos-celulares-secuestran-nuestra-mente","status":"publish","type":"post","link":"https:\/\/notinor.com\/jujuy\/de-que-manera-los-telefonos-celulares-secuestran-nuestra-mente\/","title":{"rendered":"De qu\u00e9 manera los tel\u00e9fonos celulares secuestran nuestra mente"},"content":{"rendered":"<div id=\"f0tLxxzWcbD6xq\">\n<div>\n<header>Hace un cuarto de siglo la popularizaci\u00f3n de internet prometi\u00f3 una humanidad m\u00e1s comunicada, m\u00e1s informada y m\u00e1s inteligente. Sin embargo, el dispositivo hoy universal e imprescindible hace que la gente se concentre menos, guarde menos informaci\u00f3n y sea menos inteligente.<\/header>\n<\/div>\n<\/div>\n<div id=\"fFsvM81WcbD6xq\">\n<div>\n<div><\/div>\n<\/div>\n<\/div>\n<div id=\"c7bZ002WcbD6xq\">\n<div id=\"f0H4ywiWcbD6xq\">\n<div id=\"article-body\">\n<div id=\"article-content\">\n<div>\n<figure>\n<div>\n<div><\/div>\n<p><img decoding=\"async\" loading=\"lazy\" id=\"VWZAAQDJIVGS7PHAKRTJT3YWWM\" src=\"https:\/\/www.infobae.com\/new-resizer\/7_Ld1YYgBz6OAZ1aZgqwlqM6R5k=\/600x0\/filters:quality(100)\/s3.amazonaws.com\/arc-wordpress-client-uploads\/infobae-wp\/wp-content\/uploads\/2017\/08\/18111020\/personas-celular-smartphone-SF-1.jpg\" alt=\"(IStock)\" width=\"750\" height=\"500.8928571428571\" data-url=\"http:\/\/www.infobae.com\/america\/tecno\/2017\/10\/11\/de-que-manera-los-telefonos-celulares-secuestran-nuestra-mente\/%23VWZAAQDJIVGS7PHAKRTJT3YWWM\" data-original=\"https:\/\/www.infobae.com\/new-resizer\/7_Ld1YYgBz6OAZ1aZgqwlqM6R5k=\/600x0\/filters:quality(100)\/s3.amazonaws.com\/arc-wordpress-client-uploads\/infobae-wp\/wp-content\/uploads\/2017\/08\/18111020\/personas-celular-smartphone-SF-1.jpg\" \/><\/div><figcaption>(IStock)<\/figcaption><\/figure>\n<\/div>\n<div>\n<div>\n<p>Los\u00a0usuarios promedio de un tel\u00e9fono\u00a0celular\u00a0lo\u00a0emplean 80 veces cada d\u00eda, o casi 30.000 veces en un a\u00f1o.\u00a0Seg\u00fan una\u00a0encuesta\u00a0de Gallup, la mitad de ellos\u00a0no se imaginan ya la vida sin el\u00a0dispositivo.<\/p>\n<\/div>\n<\/div>\n<div>\n<div>\n<p>Mantienen\u00a0el aparato\u00a0siempre a mano, como un\u00a0amigo inseparable, o un secretario o un gur\u00fa. Para leer\u00a0mensajes, para consultar\u00a0aplicaciones, para atender a algunas de sus alertas un mont\u00f3n de veces por d\u00eda. \"El tel\u00e9fono inteligente se ha convertido en un dep\u00f3sito del ser, registra y distribuye las palabras, los sonidos y las im\u00e1genes que definen c\u00f3mo pensamos, qu\u00e9 experiencias vivimos y qui\u00e9nes somos\", escribi\u00f3\u00a0Nicholas Carr\u00a0en\u00a0Wall Street Journal\u00a0(WSJ).<\/p>\n<\/div>\n<\/div>\n<div>\n<figure>\n<div>\n<div><\/div>\n<p><img decoding=\"async\" loading=\"lazy\" id=\"3W3B6RJRPJE3NNE5JUNFYHLQ2U\" src=\"https:\/\/www.infobae.com\/new-resizer\/JRnwRNpgeiWcQqBTZgJP6A3Jmfo=\/600x0\/filters:quality(100)\/s3.amazonaws.com\/arc-wordpress-client-uploads\/infobae-wp\/wp-content\/uploads\/2017\/08\/18111031\/personas-celular-smartphone-SF-3.jpg\" alt=\"\" width=\"750\" height=\"500.0\" data-url=\"http:\/\/www.infobae.com\/america\/tecno\/2017\/10\/11\/de-que-manera-los-telefonos-celulares-secuestran-nuestra-mente\/%233W3B6RJRPJE3NNE5JUNFYHLQ2U\" data-original=\"https:\/\/www.infobae.com\/new-resizer\/JRnwRNpgeiWcQqBTZgJP6A3Jmfo=\/600x0\/filters:quality(100)\/s3.amazonaws.com\/arc-wordpress-client-uploads\/infobae-wp\/wp-content\/uploads\/2017\/08\/18111031\/personas-celular-smartphone-SF-3.jpg\" \/><\/div><figcaption><\/figcaption><\/figure>\n<\/div>\n<div>\n<div>\n<p>Eso explica por qu\u00e9 el tel\u00e9fono m\u00f3vil causa tanta angustia entre los usuarios, que son\u00a0casi tantos como la poblaci\u00f3n del mundo: actualmente existen\u00a06.800 millones de suscripciones a celulares, con una penetraci\u00f3n de\u00a096 personas cada 100.<\/p>\n<\/div>\n<\/div>\n<div>\n<div id=\"\">\n<div id=\"inline\" data-slot-name=\"inline\" data-mobile-display=\"true\" data-desktop-display=\"true\" data-google-query-id=\"CI_kmpfb6NYCFRaDkQody5YB_A\">\n<div id=\"google_ads_iframe_\/1058609\/america\/tecno\/nota\/inline_0__container__\"><iframe id=\"google_ads_iframe_\/1058609\/america\/tecno\/nota\/inline_0\" title=\"3rd party ad content\" name=\"google_ads_iframe_\/1058609\/america\/tecno\/nota\/inline_0\" width=\"1\" height=\"1\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/div>\n<\/div>\n<div><\/div>\n<\/div>\n<div>\n<p>Carr \u2014autor de\u00a0The Shallows\u00a0y\u00a0Utopia Is Creepy, entre otros libros\u2014\u00a0se pregunt\u00f3 qu\u00e9 sucede en la mente humana cuando se genera esa\u00a0codependencia\u00a0entre la percepci\u00f3n del mundo y un objeto que se ubica como un intermediario para comprenderlo. Encontr\u00f3 muchos trabajos cient\u00edficos al respecto, que le dejaron la\u00a0impresi\u00f3n de que esa relaci\u00f3n entre las personas y sus tel\u00e9fonos \"es a la vez fascinante e inquietante\".<\/p>\n<\/div>\n<\/div>\n<div>\n<figure>\n<div>\n<div><\/div>\n<p><img decoding=\"async\" loading=\"lazy\" id=\"IB5WD2PE5FGDXDEMQRBZ5NIYKM\" src=\"https:\/\/www.infobae.com\/new-resizer\/EEzx7pTja0Qf7VFPWQ07j6b3dME=\/600x0\/filters:quality(100)\/s3.amazonaws.com\/arc-wordpress-client-uploads\/infobae-wp\/wp-content\/uploads\/2017\/08\/11164811\/Colectivo-celular-leer-1920-3.jpg\" alt=\"(iStock)\" width=\"750\" height=\"422.32142857142856\" data-url=\"http:\/\/www.infobae.com\/america\/tecno\/2017\/10\/11\/de-que-manera-los-telefonos-celulares-secuestran-nuestra-mente\/%23IB5WD2PE5FGDXDEMQRBZ5NIYKM\" data-original=\"https:\/\/www.infobae.com\/new-resizer\/EEzx7pTja0Qf7VFPWQ07j6b3dME=\/600x0\/filters:quality(100)\/s3.amazonaws.com\/arc-wordpress-client-uploads\/infobae-wp\/wp-content\/uploads\/2017\/08\/11164811\/Colectivo-celular-leer-1920-3.jpg\" \/><\/div><figcaption>(iStock)<\/figcaption><\/figure>\n<\/div>\n<div>\n<div>\n<p>En primer lugar, destac\u00f3 que\u00a0la forma en que los celulares dan forma a los pensamientos\u00a0no se limita al momento en que se los usa.\u00a0Eso importa porque una de\u00a0las consecuencias universales del uso de m\u00f3viles es\u00a0la\u00a0dispersi\u00f3n, que debilita el intelecto.<\/p>\n<\/div>\n<\/div>\n<div>\n<div>\n<p>Seg\u00fan un estudio de la\u00a0Revista de Psicolog\u00eda Experimental, si el tel\u00e9fono suena o vibra cuando una persona est\u00e1 enfrascada en\u00a0una actividad,\u00a0inmediatamente su concentraci\u00f3n se pierde y la actividad se afecta. Lo m\u00e1s asombroso es que\u00a0eso sucede atienda o no el mensaje, la alerta o la llamada. Y seg\u00fan otro trabajo sobre la mediaci\u00f3n digital,\u00a0cuando alguien escucha su tel\u00e9fono pero no puede responderlo, le sube la presi\u00f3n, se le acelera el pulso\u00a0y\u00a0capacidad de resoluci\u00f3n disminuye.<\/p>\n<\/div>\n<\/div>\n<div>\n<figure>\n<div>\n<div><\/div>\n<p><img decoding=\"async\" loading=\"lazy\" id=\"4LVAH6GEURBVTKFOXQH5TBFYNQ\" src=\"https:\/\/www.infobae.com\/new-resizer\/ZajNqLUr3T4zxxwSkvE3mFQbTqw=\/600x0\/filters:quality(100)\/s3.amazonaws.com\/arc-wordpress-client-uploads\/infobae-wp\/wp-content\/uploads\/2017\/06\/26193547\/celular-manos-1920.jpg\" alt=\"(iStock)\" width=\"750\" height=\"421.42857142857144\" data-url=\"http:\/\/www.infobae.com\/america\/tecno\/2017\/10\/11\/de-que-manera-los-telefonos-celulares-secuestran-nuestra-mente\/%234LVAH6GEURBVTKFOXQH5TBFYNQ\" data-original=\"https:\/\/www.infobae.com\/new-resizer\/ZajNqLUr3T4zxxwSkvE3mFQbTqw=\/600x0\/filters:quality(100)\/s3.amazonaws.com\/arc-wordpress-client-uploads\/infobae-wp\/wp-content\/uploads\/2017\/06\/26193547\/celular-manos-1920.jpg\" \/><\/div><figcaption>(iStock)<\/figcaption><\/figure>\n<\/div>\n<div>\n<div>\n<p>Uno de los autores del primer estudio,\u00a0el psic\u00f3logo Adrian Ward, de la Universidad de Texas en Austin, cree que\u00a0el mero apego\u00a0al celular nos vuelve menos inteligentes. En 2015, junto a colegas de la Universidad de California en San Diego (UCSD), hizo un experimento para demostrarlo.<\/p>\n<\/div>\n<\/div>\n<div>\n<div>\n<p>Los investigadores sometieron a 520 estudiantes de UCSD a\u00a0dos pruebas de agudeza intelectual. Una med\u00eda\u00a0la\u00a0capacidad cognitiva disponible,\u00a0o cu\u00e1n completamente una persona se puede concentrar\u00a0en una tarea en particular. La\u00a0otra med\u00eda\u00a0la\u00a0inteligencia fluida, la capacidad de una persona para interpretar y resolver un problema nuevo. Para medir la influencia del celular, dividieron a los estudiantes en tres grupos: uno deb\u00eda dejar el m\u00f3vil a la vista en el escritorio; otro deb\u00eda guardarlo en la ropa o el bolso; el \u00faltimo deb\u00eda dejarlo en otra habitaci\u00f3n.<\/p>\n<\/div>\n<\/div>\n<div>\n<figure>\n<div>\n<div><\/div>\n<p><img decoding=\"async\" loading=\"lazy\" id=\"FVANFQG66RFXTOI5GTJMEWQWWY\" src=\"https:\/\/www.infobae.com\/new-resizer\/dNE6jN-JU3eWec4UXHvqYopE5R8=\/600x0\/filters:quality(100)\/s3.amazonaws.com\/arc-wordpress-client-uploads\/infobae-wp\/wp-content\/uploads\/2017\/06\/05122518\/iStock-467552972.jpg\" alt=\"(iStock)\" width=\"750\" height=\"421.42857142857144\" data-url=\"http:\/\/www.infobae.com\/america\/tecno\/2017\/10\/11\/de-que-manera-los-telefonos-celulares-secuestran-nuestra-mente\/%23FVANFQG66RFXTOI5GTJMEWQWWY\" data-original=\"https:\/\/www.infobae.com\/new-resizer\/dNE6jN-JU3eWec4UXHvqYopE5R8=\/600x0\/filters:quality(100)\/s3.amazonaws.com\/arc-wordpress-client-uploads\/infobae-wp\/wp-content\/uploads\/2017\/06\/05122518\/iStock-467552972.jpg\" \/><\/div><figcaption>(iStock)<\/figcaption><\/figure>\n<\/div>\n<div>\n<div>\n<p>\"Los resultados fueron impresionantes\", evalu\u00f3 Carr. \"En ambos ex\u00e1menes,\u00a0los individuos con el tel\u00e9fono a la vista obtuvieron los peores resultados, mientras que aquellos que dejaron su tel\u00e9fono en otra habitaci\u00f3n obtuvieron los mejores\". Los que guardaron los tel\u00e9fonos en bolsillos o bolsos quedaron en el medio.<\/p>\n<\/div>\n<\/div>\n<div>\n<div>\n<p>\"A m\u00e1s proximidad del tel\u00e9fono, menor capacidad mental\", sintetiz\u00f3 el autor. Y, sin embargo, en entrevistas posteriores\u00a0ninguno de los estudiantes dijo que hubiera percibido el tel\u00e9fono como una distracci\u00f3n, sino que en general ni siquiera hab\u00edan pensado en \u00e9l. Pero se sabe que el simple acto de\u00a0reprimir \u2014conscientemente o no\u2014 el deseo de mirar la pantalla del m\u00f3vil puede debilitar el pensamiento.<\/p>\n<\/div>\n<\/div>\n<div>\n<figure>\n<div>\n<div><\/div>\n<p><img decoding=\"async\" loading=\"lazy\" id=\"ABVMOYKJHZCCHFRCCETKH6I3CY\" src=\"https:\/\/www.infobae.com\/new-resizer\/4p4CLut2j2VkQ3CiLT8Yo5wUFQ4=\/600x0\/filters:quality(100)\/s3.amazonaws.com\/arc-wordpress-client-uploads\/infobae-wp\/wp-content\/uploads\/2017\/01\/17123949\/celulares-SF-16-iPhone-5.jpg\" alt=\"\" width=\"750\" height=\"422.32142857142856\" data-url=\"http:\/\/www.infobae.com\/america\/tecno\/2017\/10\/11\/de-que-manera-los-telefonos-celulares-secuestran-nuestra-mente\/%23ABVMOYKJHZCCHFRCCETKH6I3CY\" data-original=\"https:\/\/www.infobae.com\/new-resizer\/4p4CLut2j2VkQ3CiLT8Yo5wUFQ4=\/600x0\/filters:quality(100)\/s3.amazonaws.com\/arc-wordpress-client-uploads\/infobae-wp\/wp-content\/uploads\/2017\/01\/17123949\/celulares-SF-16-iPhone-5.jpg\" \/><\/div><figcaption><\/figcaption><\/figure>\n<\/div>\n<div>\n<div>\n<p>En un art\u00edculo publicado en la\u00a0Revista de la Asociaci\u00f3n para la Investigaci\u00f3n del Consumidor, Ward y sus colegas escribieron que\u00a0\"la integraci\u00f3n de los\u00a0smartphones\u00a0en la vida cotidiana\" parece causar \"un drenaje\u00a0mental\"\u00a0que puede\u00a0disminuir las capacidades mentales m\u00e1s importantes, como \"el aprendizaje, el razonamiento l\u00f3gico, el pensamiento abstracto, la resoluci\u00f3n de problemas y la creatividad\".<\/p>\n<\/div>\n<\/div>\n<div>\n<div>\n<p>Carr revel\u00f3 que el desempe\u00f1o intelectual no es el\u00a0\u00fanico lesionado por los m\u00f3viles.\u00a0\"La sociabilidad y las relaciones tambi\u00e9n sufren\", explic\u00f3, y cit\u00f3 un estudio de la Universidad de Essex (Reino Unido), que solicit\u00f3 a 142 participantes\u00a0divididos en dos grupos \u2014en uno, las personas llevaban sus tel\u00e9fonos; en el otro, no\u2014\u00a0que hablaran de a dos en privado durante 10 minutos.<\/p>\n<\/div>\n<\/div>\n<div>\n<figure>\n<div>\n<div><\/div>\n<p><img decoding=\"async\" loading=\"lazy\" id=\"YLVHVWWG6BH3LCM62HMLKYGRKI\" src=\"https:\/\/www.infobae.com\/new-resizer\/cqC6mVfyyVoZEmMj_rUcG7j9Vpc=\/600x0\/filters:quality(100)\/s3.amazonaws.com\/arc-wordpress-client-uploads\/infobae-wp\/wp-content\/uploads\/2016\/11\/29150808\/Usuario-celular-queja-enojo-enojado-1920-3.jpg\" alt=\"(iStock)\" width=\"750\" height=\"422.32142857142856\" data-url=\"http:\/\/www.infobae.com\/america\/tecno\/2017\/10\/11\/de-que-manera-los-telefonos-celulares-secuestran-nuestra-mente\/%23YLVHVWWG6BH3LCM62HMLKYGRKI\" data-original=\"https:\/\/www.infobae.com\/new-resizer\/cqC6mVfyyVoZEmMj_rUcG7j9Vpc=\/600x0\/filters:quality(100)\/s3.amazonaws.com\/arc-wordpress-client-uploads\/infobae-wp\/wp-content\/uploads\/2016\/11\/29150808\/Usuario-celular-queja-enojo-enojado-1920-3.jpg\" \/><\/div><figcaption>(iStock)<\/figcaption><\/figure>\n<\/div>\n<div>\n<div>\n<p>A continuaci\u00f3n las personas hicieron pruebas de afinidad, confianza y empat\u00eda. \u00a0\"Tan s\u00f3lo\u00a0la presencia de los m\u00f3viles\u00a0\u2014publicaron los investigadores en la\u00a0Revista sobre las Relaciones Sociales y Personales\u2014\u00a0inhibi\u00f3 el desarrollo de la proximidad interpersonal y la confianza, y disminuy\u00f3 el alcance de la empat\u00eda y la comprensi\u00f3n entre los individuos\".<\/p>\n<\/div>\n<\/div>\n<div>\n<div>\n<p>Dado que la mente humana no es s\u00f3lo un sistema de pensamiento, sino tambi\u00e9n\u00a0un sistema de percepci\u00f3n, \"puede ser\u00a0manipulada por fuerzas externas de las que ni siquiera somos conscientes\", observ\u00f3\u00a0Carr. Las advertencias sobre la influencia de los medios no son nuevas, pero\u00a0lo que puede hacer la nueva tecnolog\u00eda m\u00f3vil no tiene precedentes.<\/p>\n<\/div>\n<\/div>\n<div>\n<figure>\n<div>\n<div><\/div>\n<p><img decoding=\"async\" loading=\"lazy\" id=\"6MVRITKWNVB5DBWXYXJ6CAMW5A\" src=\"https:\/\/www.infobae.com\/new-resizer\/Lkark_8p0wh0jfjMuvcaGCjzm1o=\/600x0\/filters:quality(100)\/s3.amazonaws.com\/arc-wordpress-client-uploads\/infobae-wp\/wp-content\/uploads\/2016\/10\/06121731\/iStock_83243457_MEDIUM.jpg\" alt=\"(Istock)\" width=\"750\" height=\"988.4169884169884\" data-url=\"http:\/\/www.infobae.com\/america\/tecno\/2017\/10\/11\/de-que-manera-los-telefonos-celulares-secuestran-nuestra-mente\/%236MVRITKWNVB5DBWXYXJ6CAMW5A\" data-original=\"https:\/\/www.infobae.com\/new-resizer\/Lkark_8p0wh0jfjMuvcaGCjzm1o=\/600x0\/filters:quality(100)\/s3.amazonaws.com\/arc-wordpress-client-uploads\/infobae-wp\/wp-content\/uploads\/2016\/10\/06121731\/iStock_83243457_MEDIUM.jpg\" \/><\/div><figcaption>(Istock)<\/figcaption><\/figure>\n<\/div>\n<div>\n<div>\n<p>El tel\u00e9fono est\u00e1 lleno de formas de informaci\u00f3n y funciones \u00fatiles y de entretenimiento.\u00a0\"Act\u00faa como lo que Ward llama 'un est\u00edmulo superior a lo normal', que puede 'secuestrar' la atenci\u00f3n\u00a0cuando es parte\u00a0de nuestro entorno, algo que siempre es\", public\u00f3 el\u00a0WSJ.<\/p>\n<\/div>\n<\/div>\n<div>\n<div>\n<p>Si la\u00a0popularizaci\u00f3n de internet trajo la promesa de una humanidad m\u00e1s inteligente, m\u00e1s informada, m\u00e1s razonadora, \"hoy sabemos que no es tan simple\", advirti\u00f3 el autor. As\u00ed como el medio da forma al contenido del mensaje,\u00a0\"el modo en que se dise\u00f1a y se usa un dispositivo ejerce al menos tanta influencia sobre nuestras mentes como la informaci\u00f3n que el dispositivo ofrece\".<\/p>\n<\/div>\n<\/div>\n<div>\n<figure>\n<div>\n<div><\/div>\n<p><img decoding=\"async\" loading=\"lazy\" id=\"UIZN5DANYJCLLPCJR7DUO4ZTXI\" src=\"https:\/\/www.infobae.com\/new-resizer\/U5jQYm4b-bdH1UlDQTX3p1QYltM=\/600x0\/filters:quality(100)\/s3.amazonaws.com\/arc-wordpress-client-uploads\/infobae-wp\/wp-content\/uploads\/2016\/09\/22162740\/gente-celular-1920-1.jpg\" alt=\"\" width=\"750\" height=\"422.32142857142856\" data-url=\"http:\/\/www.infobae.com\/america\/tecno\/2017\/10\/11\/de-que-manera-los-telefonos-celulares-secuestran-nuestra-mente\/%23UIZN5DANYJCLLPCJR7DUO4ZTXI\" data-original=\"https:\/\/www.infobae.com\/new-resizer\/U5jQYm4b-bdH1UlDQTX3p1QYltM=\/600x0\/filters:quality(100)\/s3.amazonaws.com\/arc-wordpress-client-uploads\/infobae-wp\/wp-content\/uploads\/2016\/09\/22162740\/gente-celular-1920-1.jpg\" \/><\/div><figcaption><\/figcaption><\/figure>\n<\/div>\n<div>\n<div>\n<p>Es decir que,\u00a0por extra\u00f1o que parezca, es posible que la tecnolog\u00eda reduzca el conocimiento y la comprensi\u00f3n de los seres humanos. Dos manifestaciones han llamado ya la atenci\u00f3n:\u00a0la descarga de informaci\u00f3n\u00a0(cada vez se recuerda menos, ya que todo se puede consultar en el m\u00f3vil) y\u00a0la incapacidad para discriminar si la mente o el aparato generaron la informaci\u00f3n.<\/p>\n<\/div>\n<\/div>\n<div>\n<div>\n<p>La iron\u00eda, resalt\u00f3 Carr, es que las cualidades m\u00e1s atractivas\u00a0del celular son tambi\u00e9n las que pueden secuestrar las mentes. \"Los fabricantes de tel\u00e9fonos, como Apple y Samsung, y los creadores de\u00a0apps, como Facebook y Google, dise\u00f1an sus productos para que consuman tanto de nuestra atenci\u00f3n como puedan durante cada una de nuestras horas del d\u00eda, y les agradecemos comprando millones de aparatos\u00a0y descargando miles de millones de aplicaciones cada a\u00f1o\".<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Hace un cuarto de siglo la popularizaci\u00f3n de internet prometi\u00f3 una humanidad m\u00e1s comunicada, m\u00e1s informada y m\u00e1s inteligente. Sin embargo, el dispositivo hoy universal e imprescindible hace que la gente se concentre menos, guarde menos informaci\u00f3n y sea menos inteligente. (IStock) Los\u00a0usuarios promedio de un tel\u00e9fono\u00a0celular\u00a0lo\u00a0emplean 80 veces cada d\u00eda, o casi 30.000 veces [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":139565,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_stopmodifiedupdate":false,"_modified_date":"","inline_featured_image":false},"categories":[16],"tags":[],"jetpack_featured_media_url":"https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2017\/10\/1127.jpg","_links":{"self":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts\/139564"}],"collection":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/comments?post=139564"}],"version-history":[{"count":1,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts\/139564\/revisions"}],"predecessor-version":[{"id":139566,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts\/139564\/revisions\/139566"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/media\/139565"}],"wp:attachment":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/media?parent=139564"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/categories?post=139564"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/tags?post=139564"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}