{"id":135096,"date":"2017-09-13T19:59:13","date_gmt":"2017-09-13T22:59:13","guid":{"rendered":"http:\/\/notinor.com\/jujuy\/?p=135096"},"modified":"2017-09-13T19:59:13","modified_gmt":"2017-09-13T22:59:13","slug":"inscriben-para-el-trail-2-desafio-por-las-yungas-corriendo-voy","status":"publish","type":"post","link":"https:\/\/notinor.com\/jujuy\/inscriben-para-el-trail-2-desafio-por-las-yungas-corriendo-voy\/","title":{"rendered":"Inscriben para el Trail 2\u00b0 Desaf\u00edo \u201cPor las Yungas Corriendo Voy\u201d"},"content":{"rendered":"<p><a href=\"http:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2017\/09\/Circuito-de-7-km.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter wp-image-135099 size-full\" src=\"http:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2017\/09\/Circuito-de-7-km.jpg\" alt=\"Circuito-de-7-km\" width=\"650\" height=\"555\" srcset=\"https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2017\/09\/Circuito-de-7-km.jpg 650w, https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2017\/09\/Circuito-de-7-km-300x256.jpg 300w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/><\/a><\/p>\n<p>Por mayores informes e inscripciones, los interesados pueden dirigirse a dependencias de la Secretar\u00eda de Deportes y Recreaci\u00f3n ubicada en avenida Senador P\u00e9rez N\u00b0 208, de 7:00 a 13:00 horas, o comunicarse a los tel\u00e9fonos 0388 4221310 \/ 09. Tambi\u00e9n pueden acudir al Centro de Visitantes\u00a0 Ledesma calle Ingeniero Luis M. Blaquier N\u00b0 422 Ledesma tel\u00e9fono\u00a0 0388 429440; o a la Intendencia Parque Nacional Calilegua, calle Marinero L\u00f3pez S\/ N Calilegua, tel\u00e9fono 03886 _ 422046 calilegua@apn.gov.ar<\/p>\n<p>En este evento tendr\u00e1n la oportunidad de participar adolescentes desde los 14 a\u00f1os y personas de distintas edades de acuerdo a las categor\u00edas y pruebas previstas para la competencia, de 20 km Competitiva, 11 km Participativa, 7 km Integraci\u00f3n y Trekking.<\/p>\n<p>Para la prueba de integraci\u00f3n de 7 Km: Cadetes (14 y 15 a\u00f1os), Menores (16 y 17 a\u00f1os), Libre de 18 a\u00f1os en adelante.<\/p>\n<p>Para la prueba participativa de 11 Km: Juveniles (18y 19 a\u00f1os), Libres (20 a 59 a\u00f1os) y Veteranos \u201cC\u201d (60 a\u00f1os en adelante).<\/p>\n<p>Para la prueba competitiva de 20 Km: Mayores \u201cA\u201d (20 a 29 a\u00f1os), Mayores \u201cB\u201d (30 a 39 a\u00f1os), Veteranos \u201cA\u201d\u00a0 (40 a 49 a\u00f1os),Veteranos \u201cB\u201d\u00a0 (50 a 59 a\u00f1os), y para Trekking de 3 Km mayores de edad.<\/p>\n<p>El Trail 2\u00b0 Desaf\u00edo \u201cPor las Yungas Corriendo Voy\u201d se llevar\u00e1 a cabo por segundo a\u00f1o consecutivo enmarcado en el programa Corriendo Voy que lleva adelante la Secretar\u00eda de Deportes y Recreaci\u00f3n, y a trav\u00e9s del trabajo conjunto con Administraci\u00f3n de Parques Nacionales \u2013 Parque Nacional Calilegua y Empresa Ledesma.<\/p>\n<p>La Largada<\/p>\n<p>El domingo 17 de septiembre d\u00eda del evento la largada ser\u00e1 a las 9 de la ma\u00f1ana desde Santuario Virgen de Guadalupe Km 6, Camino Parque Nacional Calilegua Ruta 83.<\/p>\n<p>Previamente desde las 8 horas se realizar\u00e1n las acreditaciones para posteriormente realizar la apertura del evento y posterior lectura de la Carta del Corredor dando indicaciones t\u00e9cnicas y organizativas adem\u00e1s de detalles de los distintos circuitos.<\/p>\n<p><a href=\"http:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2017\/09\/Circuito-de-10-km.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter wp-image-135100 size-full\" src=\"http:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2017\/09\/Circuito-de-10-km.jpg\" alt=\"Circuito-de-10-km\" width=\"650\" height=\"516\" srcset=\"https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2017\/09\/Circuito-de-10-km.jpg 650w, https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2017\/09\/Circuito-de-10-km-300x238.jpg 300w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por mayores informes e inscripciones, los interesados pueden dirigirse a dependencias de la Secretar\u00eda de Deportes y Recreaci\u00f3n ubicada en avenida Senador P\u00e9rez N\u00b0 208, de 7:00 a 13:00 horas, o comunicarse a los tel\u00e9fonos 0388 4221310 \/ 09. Tambi\u00e9n pueden acudir al Centro de Visitantes\u00a0 Ledesma calle Ingeniero Luis M. Blaquier N\u00b0 422 Ledesma [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":135098,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_stopmodifiedupdate":false,"_modified_date":"","inline_featured_image":false},"categories":[4],"tags":[],"jetpack_featured_media_url":"https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2017\/09\/Trail-2do-des-por-las-yungas-1024x722-1.jpg","_links":{"self":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts\/135096"}],"collection":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/comments?post=135096"}],"version-history":[{"count":2,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts\/135096\/revisions"}],"predecessor-version":[{"id":135101,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts\/135096\/revisions\/135101"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/media\/135098"}],"wp:attachment":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/media?parent=135096"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/categories?post=135096"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/tags?post=135096"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}