{"id":135087,"date":"2017-09-13T19:50:24","date_gmt":"2017-09-13T22:50:24","guid":{"rendered":"http:\/\/notinor.com\/jujuy\/?p=135087"},"modified":"2017-09-13T19:50:47","modified_gmt":"2017-09-13T22:50:47","slug":"jujuy-nuevamente-en-la-vidriera-nacional-de-diseno","status":"publish","type":"post","link":"https:\/\/notinor.com\/jujuy\/jujuy-nuevamente-en-la-vidriera-nacional-de-diseno\/","title":{"rendered":"Jujuy nuevamente en la vidriera Nacional de Dise\u00f1o"},"content":{"rendered":"<figure id=\"attachment_135093\" aria-describedby=\"caption-attachment-135093\" style=\"width: 690px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2017\/09\/stand.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-135093 size-full\" src=\"http:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2017\/09\/stand.jpg\" alt=\"????????????????????????????????????\" width=\"690\" height=\"529\" srcset=\"https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2017\/09\/stand.jpg 690w, https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2017\/09\/stand-300x230.jpg 300w\" sizes=\"(max-width: 690px) 100vw, 690px\" \/><\/a><figcaption id=\"caption-attachment-135093\" class=\"wp-caption-text\">????????????????????????????????????<\/figcaption><\/figure>\n<p>La cartera oficial viabiliz\u00f3 nuevamente la participaci\u00f3n local en uno de los eventos m\u00e1s importantes del rubro, en Argentina y Latinoam\u00e9rica.\u00a0 En esta oportunidad, la provincia contar\u00e1 con un stand de 50 metros cuadrados, donde 10 dise\u00f1adores juje\u00f1os podr\u00e1n exponer y comercializar sus productos a la altura de sus pares nacionales.<\/p>\n<p>Cabe recordar que los art\u00edculos que representar\u00e1n al dise\u00f1o de esta regi\u00f3n del pa\u00eds fueron previamente seleccionados en una curadur\u00eda llevada a cabo en ciudad capital, a cargo de los prestigiosos expertos Marcela Molinari y Benito Fern\u00e1ndez.<\/p>\n<p>En tanto, quienes en esas fechas se encuentren en la ciudad de Buenos Aires y deseen visitar la feria, pueden comunicarse a los tel\u00e9fonos 0388 -155845041 o 0388- 154447071 para recibir la entrada correspondiente, y acompa\u00f1ar in situ a los exponentes de Jujuy.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La cartera oficial viabiliz\u00f3 nuevamente la participaci\u00f3n local en uno de los eventos m\u00e1s importantes del rubro, en Argentina y Latinoam\u00e9rica.\u00a0 En esta oportunidad, la provincia contar\u00e1 con un stand de 50 metros cuadrados, donde 10 dise\u00f1adores juje\u00f1os podr\u00e1n exponer y comercializar sus productos a la altura de sus pares nacionales. Cabe recordar que los [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":135091,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_stopmodifiedupdate":false,"_modified_date":"","inline_featured_image":false},"categories":[13],"tags":[],"jetpack_featured_media_url":"https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2017\/09\/STAND-PURO-DISE\u00d1O-1140x705.jpg","_links":{"self":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts\/135087"}],"collection":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/comments?post=135087"}],"version-history":[{"count":3,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts\/135087\/revisions"}],"predecessor-version":[{"id":135095,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts\/135087\/revisions\/135095"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/media\/135091"}],"wp:attachment":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/media?parent=135087"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/categories?post=135087"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/tags?post=135087"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}