{"id":135082,"date":"2017-09-13T19:47:02","date_gmt":"2017-09-13T22:47:02","guid":{"rendered":"http:\/\/notinor.com\/jujuy\/?p=135082"},"modified":"2017-09-13T19:47:03","modified_gmt":"2017-09-13T22:47:03","slug":"alerta-en-mexico-por-la-formacion-de-la-tormenta-tropical-max-en-el-oceano-pacifico","status":"publish","type":"post","link":"https:\/\/notinor.com\/jujuy\/alerta-en-mexico-por-la-formacion-de-la-tormenta-tropical-max-en-el-oceano-pacifico\/","title":{"rendered":"Alerta en M\u00e9xico por la formaci\u00f3n de la tormenta tropical Max en el Oc\u00e9ano Pac\u00edfico"},"content":{"rendered":"<div id=\"fKlHMF16SfH4vq\">\n<div>\n<header>Seg\u00fan el Centro Nacional de Huracanes de Estados Unidos, avanza con vientos de 65 kil\u00f3metros por hora. Se prev\u00e9 que toque tierra en Acapulco este jueves.<\/header>\n<\/div>\n<\/div>\n<div id=\"fcEfyN16SfH4vq\">\n<div>\n<div><\/div>\n<\/div>\n<\/div>\n<div id=\"c0dVmAM6SfH4vq\">\n<div id=\"fuZF7b26SfH4vq\">\n<div id=\"article-body\">\n<div id=\"article-content\">\n<div>\n<figure>\n<div>\n<div><\/div>\n<p><img decoding=\"async\" loading=\"lazy\" id=\"73WZYWZSSNFYFLOIU5QDNO2F7E\" class=\"aligncenter\" src=\"http:\/\/www.infobae.com\/new-resizer\/LE0hMAPybTxgXQhA89yiWXKDxlU=\/600x0\/s3.amazonaws.com\/arc-wordpress-client-uploads\/infobae-wp\/wp-content\/uploads\/2017\/09\/13192232\/tormenta-max.jpg?token=bar\" alt=\"\" width=\"750\" height=\"422.32142857142856\" data-url=\"http:\/\/www.infobae.com\/america\/mexico\/2017\/09\/13\/alerta-en-mexico-por-la-formacion-de-la-tormenta-tropical-max-en-el-oceano-pacifico\/%2373WZYWZSSNFYFLOIU5QDNO2F7E\" data-original=\"http:\/\/www.infobae.com\/new-resizer\/LE0hMAPybTxgXQhA89yiWXKDxlU=\/600x0\/s3.amazonaws.com\/arc-wordpress-client-uploads\/infobae-wp\/wp-content\/uploads\/2017\/09\/13192232\/tormenta-max.jpg?token=bar\" \/><\/div><figcaption><\/figcaption><\/figure>\n<\/div>\n<div>\n<div>\n<p>Este mi\u00e9rcoles en la costa sur del Pac\u00edfico mexicano se form\u00f3 la tormenta tropical Max, de acuerdo a lo informado por el Centro Nacional de Huracanes de Estados Unidos (NHC, por sus siglas en ingl\u00e9s).<\/p>\n<\/div>\n<\/div>\n<div>\n<div>\n<p>Las autoridades se\u00f1alaron que la tormenta se origin\u00f3\u00a0a unos 185 kil\u00f3metros del oeste-suroeste de Acapulco.<\/p>\n<\/div>\n<\/div>\n<div>\n<div>\n<p>Asimismo,\u00a0Max avanza en su recorrido con vientos de 65 kil\u00f3metros\u00a0y se mueve del este-noreste a 6 kil\u00f3metros por hora.<\/p>\n<\/div>\n<\/div>\n<div>\n<div>\n<p>El gobierno mexicano emiti\u00f3 una alerta de tormenta tropical para la costa desde el complejo Zihuatanejo hacia Punto Maldonado al este.<\/p>\n<\/div>\n<\/div>\n<div>\n<div id=\"\">\n<div id=\"inline\" data-slot-name=\"inline\" data-mobile-display=\"true\" data-desktop-display=\"true\" data-google-query-id=\"CNTTnrKdo9YCFU0RkQodfHQJTA\">\n<div id=\"google_ads_iframe_\/1058609\/america\/mexico\/nota\/inline_0__container__\"><iframe id=\"google_ads_iframe_\/1058609\/america\/mexico\/nota\/inline_0\" title=\"3rd party ad content\" name=\"google_ads_iframe_\/1058609\/america\/mexico\/nota\/inline_0\" width=\"1\" height=\"1\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/div>\n<\/div>\n<div><\/div>\n<\/div>\n<div>\n<p>No obstante,\u00a0no se espera que Max cobre mucha fuerza en su avance. Se prev\u00e9 que puede llegar a tocar tierra en Acapulco este jueves.<\/p>\n<\/div>\n<\/div>\n<div>\n<div>\n<p>El Centro de Huracanes advirti\u00f3 que la tormenta podr\u00eda provocar lluvias torrenciales sobre las \u00e1reas costeras afectadas por el terremoto de magnitud 8,1 que golpe\u00f3 a M\u00e9xico la semana pasada.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Seg\u00fan el Centro Nacional de Huracanes de Estados Unidos, avanza con vientos de 65 kil\u00f3metros por hora. Se prev\u00e9 que toque tierra en Acapulco este jueves. Este mi\u00e9rcoles en la costa sur del Pac\u00edfico mexicano se form\u00f3 la tormenta tropical Max, de acuerdo a lo informado por el Centro Nacional de Huracanes de Estados Unidos [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":135088,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_stopmodifiedupdate":false,"_modified_date":"","inline_featured_image":false},"categories":[6],"tags":[],"jetpack_featured_media_url":"https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2017\/09\/03.jpg","_links":{"self":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts\/135082"}],"collection":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/comments?post=135082"}],"version-history":[{"count":1,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts\/135082\/revisions"}],"predecessor-version":[{"id":135090,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts\/135082\/revisions\/135090"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/media\/135088"}],"wp:attachment":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/media?parent=135082"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/categories?post=135082"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/tags?post=135082"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}