{"id":116316,"date":"2017-05-06T14:13:19","date_gmt":"2017-05-06T17:13:19","guid":{"rendered":"http:\/\/notinor.com\/jujuy\/?p=116316"},"modified":"2017-05-06T14:13:40","modified_gmt":"2017-05-06T17:13:40","slug":"san-pedro-los-familiares-de-alejandra-oscari-marchan-por-su-aparcion","status":"publish","type":"post","link":"https:\/\/notinor.com\/jujuy\/san-pedro-los-familiares-de-alejandra-oscari-marchan-por-su-aparcion\/","title":{"rendered":"San Pedro: Los familiares de Alejandra Oscari marchan por su aparci\u00f3n"},"content":{"rendered":"<p><a href=\"http:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2017\/05\/WhatsApp-Image-2017-05-06-at-12.31.44-e1494090728917.jpeg\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-large wp-image-116329\" src=\"http:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2017\/05\/WhatsApp-Image-2017-05-06-at-12.31.44-1024x768.jpeg\" alt=\"WhatsApp Image 2017-05-06 at 12.31.44\" width=\"1024\" height=\"768\" \/><\/a><\/p>\n<p>Familiares y amigos marcharon esta ma\u00f1ana por las calles de San Pedro Jujuy. Entre llantos y angustia se oy\u00f3 \u00a1Alejandra Presente!<\/p>\n<p>Alejandra Ver\u00f3nica Oscari, de 21 a\u00f1os, es de contextura delgada, mide 1,65m, es de tez trigue\u00f1a, cabello largo, lacio de color casta\u00f1o, ojos negros, boca y nariz normal, se\u00f1a particular una lunar altura labio superior.<\/p>\n<p><a href=\"http:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2017\/05\/veronica-alejandra-oscari.jpeg\"><img decoding=\"async\" loading=\"lazy\" class=\"size-full wp-image-116327 aligncenter\" src=\"http:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2017\/05\/veronica-alejandra-oscari.jpeg\" alt=\"veronica alejandra oscari\" width=\"409\" height=\"234\" srcset=\"https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2017\/05\/veronica-alejandra-oscari.jpeg 409w, https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2017\/05\/veronica-alejandra-oscari-300x172.jpeg 300w, https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2017\/05\/veronica-alejandra-oscari-408x234.jpeg 408w\" sizes=\"(max-width: 409px) 100vw, 409px\" \/><\/a><\/p>\n<p>Cabe destacar que Alejandra desapareci\u00f3 de su hogar ayer en horas de la madruga, bajo circunstancias que la polic\u00eda investiga y trata de establecer. La denuncia efectuada por su padre expresa que el se retir\u00f3 a trabajar alrededor de las 16,30 y al regresar a las 6,30 de la madrugada encontr\u00f3 la vivienda con las puertas abiertas y el celular de Alejandra tirado debajo de la cama, pero sin rastros de su hija en la casa.<\/p>\n<p>El operativo para dar con su paradero es exhaustivo. Se ruega a la comunidad aportar cualquier dato que pueda esclarecer el paradero de Alejandra Ver\u00f3nica Oscari.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Familiares y amigos marcharon esta ma\u00f1ana por las calles de San Pedro Jujuy. Entre llantos y angustia se oy\u00f3 \u00a1Alejandra Presente! Alejandra Ver\u00f3nica Oscari, de 21 a\u00f1os, es de contextura delgada, mide 1,65m, es de tez trigue\u00f1a, cabello largo, lacio de color casta\u00f1o, ojos negros, boca y nariz normal, se\u00f1a particular una lunar altura labio [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":116329,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_stopmodifiedupdate":false,"_modified_date":"","inline_featured_image":false},"categories":[4],"tags":[],"jetpack_featured_media_url":"https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2017\/05\/WhatsApp-Image-2017-05-06-at-12.31.44-e1494090728917.jpeg","_links":{"self":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts\/116316"}],"collection":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/comments?post=116316"}],"version-history":[{"count":1,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts\/116316\/revisions"}],"predecessor-version":[{"id":116330,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts\/116316\/revisions\/116330"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/media\/116329"}],"wp:attachment":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/media?parent=116316"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/categories?post=116316"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/tags?post=116316"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}