{"id":115479,"date":"2017-05-01T00:41:37","date_gmt":"2017-05-01T03:41:37","guid":{"rendered":"http:\/\/notinor.com\/jujuy\/?p=115479"},"modified":"2017-05-01T00:41:37","modified_gmt":"2017-05-01T03:41:37","slug":"centro-mujer-fue-sorprendida-cuando-sustraia-mercaderia-de-un-supermercado-entre-sus-ropas","status":"publish","type":"post","link":"https:\/\/notinor.com\/jujuy\/centro-mujer-fue-sorprendida-cuando-sustraia-mercaderia-de-un-supermercado-entre-sus-ropas\/","title":{"rendered":"\u00a0Centro: Mujer fue sorprendida cuando sustra\u00eda mercader\u00eda de un supermercado entre sus ropas"},"content":{"rendered":"<p class=\"m_2406934011673686307gmail-MsoNoSpacing\">Efectivos de la Guardia de Prevenci\u00f3n Urbana, el s\u00e1bado \u00faltimo procedieron a la demora de una adolescente, quien intento llevarse escondidas entre sus prendas de vestir mercader\u00eda de un supermercado, ubicado en el barrio centro de esta ciudad capital. La protagonista fue trasladada hacia la seccional primera.<\/p>\n<p class=\"m_2406934011673686307gmail-MsoNoSpacing\"><a href=\"http:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2017\/05\/robo-super.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-115480\" src=\"http:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2017\/05\/robo-super.jpg\" alt=\"robo super\" width=\"600\" height=\"450\" srcset=\"https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2017\/05\/robo-super.jpg 600w, https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2017\/05\/robo-super-300x225.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p class=\"m_2406934011673686307gmail-MsoNoSpacing\">\n<p class=\"m_2406934011673686307gmail-MsoNoSpacing\">El procedimiento se llev\u00f3 a cabo aproximadamente a horas 18:00, en circunstancias en que personal policial de la mencionada guardia, se encontraba realizando recorridos de prevenci\u00f3n y seguridad, fue alertada por un personal de seguridad privada, que una joven habr\u00eda intentado\u00a0 sustraer de una de las g\u00f3ndolas elementos exhibidos, de un local comercial ubicado en calle G\u00fcemes.<\/p>\n<p class=\"m_2406934011673686307gmail-MsoNoSpacing\">\n<p class=\"m_2406934011673686307gmail-MsoNoSpacing\">Al arribar al lugar los polic\u00edas, observaron a una persona de sexo femenino demorada dentro del mencionado local por personal de seguridad, quienes manifestaron que sorprendieron a la inculpada escondiendo entres sus prendas de vestir el objeto rapi\u00f1ado, intentado salir sin pagar.<\/p>\n<p class=\"m_2406934011673686307gmail-MsoNoSpacing\">\n<p class=\"m_2406934011673686307gmail-MsoNoSpacing\">Seguidamente se procedi\u00f3 al arresto y posterior traslado de la misma hacia la comisaria seccional 1era., donde quedo a disposici\u00f3n de la justicia, previa averiguaci\u00f3n de antecedentes y posterior denuncia de la parte damnificada.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Efectivos de la Guardia de Prevenci\u00f3n Urbana, el s\u00e1bado \u00faltimo procedieron a la demora de una adolescente, quien intento llevarse escondidas entre sus prendas de vestir mercader\u00eda de un supermercado, ubicado en el barrio centro de esta ciudad capital. La protagonista fue trasladada hacia la seccional primera. El procedimiento se llev\u00f3 a cabo aproximadamente a [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":115480,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_stopmodifiedupdate":false,"_modified_date":"","inline_featured_image":false},"categories":[3],"tags":[],"jetpack_featured_media_url":"https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2017\/05\/robo-super.jpg","_links":{"self":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts\/115479"}],"collection":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/comments?post=115479"}],"version-history":[{"count":1,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts\/115479\/revisions"}],"predecessor-version":[{"id":115481,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts\/115479\/revisions\/115481"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/media\/115480"}],"wp:attachment":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/media?parent=115479"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/categories?post=115479"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/tags?post=115479"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}