{"id":11132,"date":"2015-01-04T00:19:10","date_gmt":"2015-01-04T00:19:10","guid":{"rendered":"http:\/\/notinor.com\/jujuy\/?p=11132"},"modified":"2015-01-04T00:19:22","modified_gmt":"2015-01-04T00:19:22","slug":"alejandro-snopek-es-parte-del-sub-45-junto-de-sergio-massa","status":"publish","type":"post","link":"https:\/\/notinor.com\/jujuy\/alejandro-snopek-es-parte-del-sub-45-junto-de-sergio-massa\/","title":{"rendered":"Alejandro Snopek es parte del sub 45 de Sergio Massa"},"content":{"rendered":"<div id=\"readerZenv30260v1-title\" class=\"title\">El rector de la Universidad de Lomas de Zamora, Diego Molea, organiz\u00f3 en Pinamar un encuentro de Sergio Massa con intendentes y legisladores del Frente Renovador, de menos de 45 a\u00f1os.<\/div>\n<div class=\"title\">\n<p>LPO || Y agreg\u00f3: \u201cLa idea era empezar el a\u00f1o as\u00ed, encontr\u00e1ndonos junto a toda la dirigencia del Frente Renovador para transmitirle a la sociedad que la Argentina que viene ser\u00e1 mejor de la que se va. Ac\u00e1 est\u00e1 la joven dirigencia que tiene la responsabilidad de construir la Argentina que viene\u201d.<\/p>\n<p><a href=\"http:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2015\/01\/54a8413f66b52_660_360.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-11133\" src=\"http:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2015\/01\/54a8413f66b52_660_360.jpg\" alt=\"54a8413f66b52_660_360!\" width=\"660\" height=\"360\" srcset=\"https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2015\/01\/54a8413f66b52_660_360.jpg 660w, https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2015\/01\/54a8413f66b52_660_360-300x163.jpg 300w\" sizes=\"(max-width: 660px) 100vw, 660px\" \/><\/a><\/p>\n<p>Del encuentro que se realiz\u00f3 en Pinamar, participaron los diputados nacionales Adri\u00e1n P\u00e9rez y Marcelo D\u2019Alessandro. Asimismo, los intendentes Gabriel Katopodis (San Mart\u00edn), Gustavo Bevilacqua (Bah\u00eda Blanca), Ismael Bordagaray (Famatina), Mart\u00edn Caso (Rojas), Germ\u00e1n Di Cesare (Gral. Alvarado), Javier Mignaquy (Gral. Viamonte), Carlos Puglieli (San Andr\u00e9s de Giles), Marcela Passo (Gral. Lavalle), Pablo Mirolo (La Banda) y Dar\u00edo Florit (Olaeta).<\/p>\n<p>Adem\u00e1s estuvieron presentes legisladores provinciales y locales, dirigentes y referentes como Malena Galmarini, Javier Faroni, Marco Lavagna, Cecilia Moreau, Florencia Achaval, Hern\u00e1n Albizu, Adri\u00e1n Fuertes, Lucas Jaszewski, Rodrigo Alvarez, Valeria Arata, Florencia Arietto, Marcela Acu\u00f1a, Malena Baro, Jos\u00e9 Blassiotto, Lisandro Bonelli, Daniel Cassia, Rodolfo Colombo, Marita Conti, Rodrigo Estigarribia, Micaela Ferraro Medina, Sebasti\u00e1n Galmarini, Jos\u00e9 Garrido, Ramiro Guti\u00e9rrez, Patricio Hern\u00e1ndez, Patricio Hogan, Mart\u00edn Jofr\u00e9, Diego Kravetz, Diana Larraburu, Marcelo Leguizam\u00f3n, Mart\u00edn Marinucci, Gabriel Pamp\u00edn, Walter Queijeiro, Jos\u00e9 Richards, Gustavo S\u00e1enz, Alejandro Snopek, Gustavo Valls, Ger\u00f3nimo Vargas Aignasse, Luciano Ventricelli, Pablo Yanibelli y Gustavo Zavallo, entre otros.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>El rector de la Universidad de Lomas de Zamora, Diego Molea, organiz\u00f3 en Pinamar un encuentro de Sergio Massa con intendentes y legisladores del Frente Renovador, de menos de 45 a\u00f1os. LPO || Y agreg\u00f3: \u201cLa idea era empezar el a\u00f1o as\u00ed, encontr\u00e1ndonos junto a toda la dirigencia del Frente Renovador para transmitirle a la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":11133,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_stopmodifiedupdate":false,"_modified_date":"","inline_featured_image":false},"categories":[485],"tags":[],"jetpack_featured_media_url":"https:\/\/notinor.com\/jujuy\/wp-content\/uploads\/2015\/01\/54a8413f66b52_660_360.jpg","_links":{"self":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts\/11132"}],"collection":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/comments?post=11132"}],"version-history":[{"count":2,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts\/11132\/revisions"}],"predecessor-version":[{"id":11135,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/posts\/11132\/revisions\/11135"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/media\/11133"}],"wp:attachment":[{"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/media?parent=11132"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/categories?post=11132"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/notinor.com\/jujuy\/wp-json\/wp\/v2\/tags?post=11132"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}